{"id":28825,"date":"2024-09-26T15:38:01","date_gmt":"2024-09-26T07:38:01","guid":{"rendered":"https:\/\/univers.com\/il-nostro-codice-di-condotta-univers\/"},"modified":"2025-12-17T01:27:47","modified_gmt":"2025-12-16T17:27:47","slug":"il-nostro-codice-di-condotta-univers","status":"publish","type":"page","link":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/","title":{"rendered":"Il nostro Codice di Condotta | Univers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"28825\" class=\"elementor elementor-28825 elementor-3084\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3af6cecc e-flex e-con-boxed e-con e-parent\" data-id=\"3af6cecc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56638bda elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"56638bda\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Panoramica delle politiche<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b4170c8 e-con-full e-flex e-con e-parent\" data-id=\"6b4170c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-74b3f807 e-flex e-con-boxed e-con e-child\" data-id=\"74b3f807\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c440b3 e-n-tabs-mobile elementor-invisible elementor-widget elementor-widget-n-tabs\" data-id=\"6c440b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"113524915\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1135249151\" data-tab-title-id=\"e-n-tab-title-1135249151\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1135249151\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tPanoramica delle politiche\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1135249152\" data-tab-title-id=\"e-n-tab-title-1135249152\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1135249152\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tCodice di condotta\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1135249153\" data-tab-title-id=\"e-n-tab-title-1135249153\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1135249153\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tPolitica SpeakUp\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1135249154\" data-tab-title-id=\"e-n-tab-title-1135249154\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1135249154\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tDichiarazione sulla schiavit\u00f9 moderna\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1135249155\" data-tab-title-id=\"e-n-tab-title-1135249155\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1135249155\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tPolitica di pari opportunit\u00e0 di impiego\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1135249151\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1135249151\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-0e1ef2e e-con-full e-flex e-con e-child\" data-id=\"0e1ef2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f5c8a5 elementor-widget elementor-widget-text-editor\" data-id=\"7f5c8a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Costruire una cultura universale della conformit\u00e0  <\/strong><\/h2>\n<p>In Univers, dove la connessione \u00e8 tutto, \u00e8 il modo in cui realizzeremo la transizione verso l&#8217;energia verde che i nostri clienti richiedono e di cui il mondo ha bisogno. Ci impegniamo a raggiungere questo obiettivo attraverso il rigoroso rispetto delle leggi e delle normative vigenti e a fare dell&#8217;integrit\u00e0 una parte centrale del nostro DNA e della nostra cultura, in tutte le nostre operazioni, a livello universale. <\/p>\n<p>Il nostro programma di etica e conformit\u00e0, basato sul Codice di Condotta Univers, si applica a tutti i dipendenti, i dirigenti, gli amministratori e i terzi che ci rappresentano. Il Codice di Condotta stabilisce standard elevati di etica e integrit\u00e0 in tutte le nostre operazioni commerciali, senza eccezioni, e mette il nostro personale in condizione di fare scelte etiche nelle attivit\u00e0 quotidiane con i nostri vari stakeholder, comprese le comunit\u00e0 in cui operiamo. <\/p>\n<p>Il Codice di Condotta Univers \u00e8 supportato dalla nostra Politica Anticorruzione (che copre anche i regali e l&#8217;ospitalit\u00e0). Il Codice rafforza la nostra tolleranza zero nei confronti di corruzione e concussione. Il nostro programma di whistleblowing &#8220;SpeakUp&#8221; riflette il nostro impegno a &#8220;fare il bene facendo il bene&#8221; e incoraggia a parlare se qualcosa non sembra giusto. Univers non tollera ritorsioni nei confronti di qualsiasi dipendente o partner che sollevi preoccupazioni o domande in merito a comportamenti illegali o impropri osservati o sospetti o a potenziali violazioni del Codice di Condotta di Univers o di qualsiasi politica di Univers che egli ritenga ragionevolmente essersi verificate.   <\/p>\n<p>Ci sforziamo continuamente di adattare e migliorare il nostro programma di etica e conformit\u00e0 per affrontare l&#8217;evoluzione del panorama etico e legale ovunque operiamo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-164c4eb elementor-widget elementor-widget-text-editor\" data-id=\"164c4eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ultima modifica: 13 set 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1135249152\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1135249152\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-6cc1781 e-con-full e-flex e-con e-child\" data-id=\"6cc1781\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5d00df elementor-widget elementor-widget-text-editor\" data-id=\"b5d00df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><strong>1. UN MESSAGGIO DEL NOSTRO AMMINISTRATORE DELEGATO<\/strong><\/h2><p class=\"small-body\">Cari colleghi,<\/p><p class=\"small-body\">Benvenuto in Univers, dove la connessione \u00e8 tutto.<\/p><p class=\"small-body\">Colleghiamo hardware, software, beni e informazioni nel sistema di decarbonizzazione pi\u00f9 completo al mondo. Pi\u00f9 in generale, crediamo nel potere della connessione per sbloccare opportunit\u00e0, favorire una comprensione pi\u00f9 profonda e dare potere alle persone in tutto il mondo. Rafforza la solidariet\u00e0 e alimenta il nostro lavoro sulla transizione verso il net zero e tutto ci\u00f2 che verr\u00e0 dopo.    <\/p><p class=\"small-body\">La connessione si basa su relazioni, fiducia e integrit\u00e0. Oltre a fare affidamento su di noi per ottenere dati precisi, affidabili e utili per la decarbonizzazione, i nostri clienti si affidano a noi per condurre noi stessi e la nostra attivit\u00e0 con un&#8217;integrit\u00e0 impeccabile. <\/p><p class=\"small-body\">Il vero successo non \u00e8 definito solo dall&#8217;obiettivo finale, ma anche dal modo in cui ci comportiamo durante il viaggio verso quell&#8217;obiettivo. \u00c8 fondamentale che la nostra azienda sia costruita su principi di integrit\u00e0 e fiducia, per i nostri clienti, per la nostra azienda e per noi stessi. <\/p><p class=\"small-body\">La nostra tolleranza zero nei confronti di comportamenti illegali e non etici \u00e8 articolata nel nostro Codice di Condotta, che \u00e8 stato concepito per aiutarci a gestire le situazioni comuni, e talvolta insolite, che possiamo incontrare sul lavoro. Ti chiedo di leggere, comprendere e applicare il Codice di Condotta al tuo modo di operare ogni giorno, portando questi valori in tutto ci\u00f2 che fai. <\/p><p class=\"small-body\">Il Codice di Condotta sar\u00e0 il faro che guider\u00e0 il processo decisionale e creer\u00e0 fiducia tra i colleghi e i clienti. Dobbiamo essere orgogliosi di ci\u00f2 che facciamo e di come lo facciamo. <\/p><p class=\"small-body\">Grazie per aver intrapreso questo viaggio con me. Facciamo in modo che il prossimo capitolo della storia dell&#8217;Universit\u00e0 sia all&#8217;insegna di un codice di condotta etico. <\/p><p> <\/p><p class=\"small-body\">Lei Zhang<\/p><p class=\"small-body\">Amministratore delegato<\/p><p><img decoding=\"async\" src=\"https:\/\/a.storyblok.com\/f\/223827\/155x88\/0e8799f6a9\/image-1836-no-bg.png\"><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c593b1f elementor-widget elementor-widget-text-editor\" data-id=\"c593b1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"header-1\"><b>2. RISPETTIAMO IL NOSTRO CODICE DI CONDOTTA<\/b><\/h2><h3 class=\"body-large\">Mettere l&#8217;integrit\u00e0 al primo posto<\/h3><p class=\"small-body\">Fin dall&#8217;inizio ci siamo guadagnati la reputazione di essere lungimiranti, non solo per stare al passo con i cambiamenti, ma anche per guidarli. Oggi questo slancio continua e promette un futuro brillante per noi, come azienda, e per coloro che serviamo. <\/p><p class=\"small-body\">Siamo consapevoli che, mentre continuiamo a innovare e a crescere, c&#8217;\u00e8 una cosa che non deve mai cambiare: il nostro incrollabile impegno a lavorare in modo etico, onesto e nel rispetto della legge. L&#8217;integrit\u00e0 deve continuare a essere al centro del nostro DNA aziendale, anche quando cresciamo e affrontiamo nuove ambiziose sfide. Il nostro Codice di Condotta (&#8220;<b>Codice<\/b>&#8220;) \u00e8 una risorsa fondamentale in questo senso. Aiuta ognuno di noi, a prescindere dal ruolo che ricopre all&#8217;interno della nostra azienda, a:   <\/p><ul><li class=\"small-body\">Metti l&#8217;integrit\u00e0 al primo posto e mantieni i pi\u00f9 alti standard di condotta aziendale.<\/li><li class=\"small-body\">Rispettare le leggi, i regolamenti e le politiche che si applicano alla nostra attivit\u00e0, ovunque operiamo.<\/li><li class=\"small-body\">Superare le sfide etiche che possiamo affrontare sul lavoro ed evitare anche solo l&#8217;apparenza di qualcosa di improprio.<\/li><\/ul><p> <\/p><p class=\"small-body\"><i>Il nostro Codice vale per tutti noi<\/i><\/p><p class=\"small-body\">Tutti i membri di Univers, come i dipendenti (a tempo pieno e parziale), i lavoratori a contratto, i consulenti interni, i funzionari e i direttori, sono tenuti a leggere, comprendere e rispettare il nostro Codice.<\/p><p> <\/p><p class=\"small-body\"><b>Noi siamo Univers<\/b><\/p><p class=\"small-body\">Quando ci riferiamo a &#8220;Universit\u00e0&#8221;, &#8220;azienda&#8221;, &#8220;noi&#8221;, &#8220;ci&#8221; o &#8220;nostro&#8221;, intendiamo l&#8217;azienda o le aziende del gruppo Univers.<\/p><p class=\"small-body\">Anche i consulenti esterni, i partner commerciali, i distributori, i rappresentanti, gli agenti e gli intermediari che agiscono per conto di Univers (&#8220;<b>Terze Parti<\/b>&#8220;) sono tenuti a rispettare lo spirito del nostro Codice, nonch\u00e9 le disposizioni contrattuali applicabili.  <\/p><p class=\"small-body\">Coloro che supervisionano le nostre Terze Parti hanno la responsabilit\u00e0 di comunicare i nostri standard e di assicurarsi che vengano compresi. Se una Terza Parte non rispetta le nostre aspettative di etica e conformit\u00e0 o i relativi obblighi contrattuali, pu\u00f2 comportare la risoluzione del contratto.   <\/p><p> <\/p><p class=\"small-body\"><b>Il nostro impegno<\/b><\/p><p class=\"small-body\">Ci impegniamo a rispettare tutte le leggi, le norme e i regolamenti applicabili alla nostra attivit\u00e0. Poich\u00e9 il Codice non \u00e8 in grado di affrontare tutte le situazioni che potresti trovarti ad affrontare, disponiamo di altre risorse che possono esserti d&#8217;aiuto: tali risorse sono elencate nel Codice. <\/p><p class=\"small-body\">Operiamo in diversi Paesi, quindi \u00e8 importante conoscere e rispettare le diverse leggi e usanze che possono essere applicate. Pur rispettando le norme dei nostri clienti, delle Terze Parti e dei colleghi di tutto il mondo, tutti in Univers devono, come minimo, rispettare gli standard e i principi del presente Codice. Se una parte del nostro Codice \u00e8 in conflitto con una legge o un requisito locale, chiediamo consiglio all&#8217;ufficio legale e di conformit\u00e0.  <\/p><p> <\/p><p class=\"small-body\"><i>Le violazioni sono gravi<\/i><\/p><p class=\"small-body\">Violare il nostro Codice, le nostre politiche o la legge, o incoraggiare altri a farlo, espone la nostra azienda a responsabilit\u00e0 e mette a rischio la nostra reputazione. Nessun motivo, compreso il desiderio di raggiungere gli obiettivi aziendali, deve mai essere una scusa per violare il nostro Codice, le nostre politiche o la legge. <\/p><p class=\"small-body\">Se vedi o sospetti una violazione, \u00e8 tua responsabilit\u00e0 segnalarla<i>.<\/i><\/p><p class=\"small-body\"><i>Chiunque violi il nostro Codice sar\u00e0 soggetto ad azioni disciplinari, fino alla cessazione del rapporto di lavoro con Univers, nella misura massima consentita dalle leggi vigenti. Le violazioni di leggi o regolamenti possono anche comportare procedimenti e sanzioni legali, tra cui, in alcune circostanze, azioni penali. <\/i><\/p><p> <\/p><p class=\"small-body\"><i>Il feedback \u00e8 benvenuto!<\/i><\/p><p class=\"small-body\">Apprezziamo i suggerimenti volti a migliorare il nostro Codice, le nostre politiche o le nostre risorse per affrontare meglio una particolare area di rischio o questione. Promuovere un&#8217;Universit\u00e0 etica \u00e8 una responsabilit\u00e0 che tutti condividiamo. <\/p><h3> <\/h3><h3 class=\"body-large\">Comprendere le nostre responsabilit\u00e0<\/h3><p class=\"small-body\">Ognuno di noi ha una serie di responsabilit\u00e0 associate al proprio lavoro, ma tutti in Univers sono tenuti a farlo:<\/p><ul><li class=\"small-body\">Conoscere il nostro Codice, le nostre politiche aziendali e le nostre specifiche responsabilit\u00e0 lavorative e completare la formazione necessaria per il nostro ruolo.<\/li><li class=\"small-body\">Essere professionali, onesti ed etici quando conduciamo affari per conto della nostra azienda.<\/li><li class=\"small-body\">Segnalare qualsiasi violazione nota o sospetta del nostro Codice, delle nostre politiche o della legge al nostro responsabile di linea o a uno dei canali di segnalazione elencati nel nostro Codice.<\/li><li class=\"small-body\">Collabora pienamente e dici la verit\u00e0 quando rispondi a un&#8217;indagine, a un&#8217;inchiesta o a un audit e non alterare o distruggere mai i documenti in risposta a un&#8217;indagine o quando si prevede un&#8217;indagine. La collaborazione con un&#8217;indagine o un audit pu\u00f2 includere la concessione dell&#8217;accesso o del possesso del tuo laptop aziendale, del disco rigido del computer o delle e-mail all&#8217;azienda per l&#8217;esame nell&#8217;ambito di un&#8217;indagine o di un audit. <\/li><\/ul><div> <\/div><p class=\"small-body\">I leader danno il tono al modo in cui gli affari vengono svolti. Coloro che gestiscono o supervisionano gli altri hanno la responsabilit\u00e0 di: <\/p><ul><li class=\"small-body\">Agiscono come un modello e una risorsa per il proprio team. Devono conoscere il Codice, farvi riferimento e utilizzarlo per guidare e informare le discussioni sui dilemmi etici e sulle situazioni difficili, al fine di instillare una cultura dell&#8217;integrit\u00e0. <\/li><li class=\"small-body\">Creare un ambiente di lavoro rispettoso, in cui i dipendenti siano apprezzati e si sentano a proprio agio nel fare domande e dare voce alle loro preoccupazioni.<\/li><li class=\"small-body\">Ascoltano attentamente quando un problema viene portato alla loro attenzione, assicurandosi che venga trattato in modo serio e confidenziale, e intraprendono azioni di follow-up appropriate.<\/li><li class=\"small-body\">Conoscere i limiti della propria autorit\u00e0, non intraprendendo mai azioni che vadano oltre la propria autorit\u00e0 o delegando l&#8217;autorit\u00e0 a qualcuno che si teme possa intraprendere una condotta illegale o non etica.  <\/li><\/ul><div> <\/div><div> <\/div><h3 class=\"body-large\">Prendere buone decisioni<\/h3><p class=\"small-body\">Anche se le nostre intenzioni sono buone, a volte l&#8217;azione o la decisione giusta non \u00e8 ovvia. In queste situazioni:   <\/p><p class=\"small-body\"><b>Chiediamo a noi stessi<\/b><\/p><ul><li class=\"small-body\">Sto seguendo i valori di Univers?<\/li><li class=\"small-body\">Vorrei che i miei colleghi, i miei amici, la mia famiglia o il pubblico in generale lo leggessero?<\/li><li class=\"small-body\">Questo sostiene la reputazione di Univers di condurre gli affari in modo etico?<\/li><\/ul><p class=\"small-body\">Se hai risposto &#8220;s\u00ec&#8221; a tutte queste domande, allora probabilmente la decisione di andare avanti \u00e8 giusta.  <\/p><p> <\/p><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Mi trovo di fronte a una situazione in cui fare la cosa giusta potrebbe compromettere la redditivit\u00e0 della nostra azienda. Cosa devo fare? <\/i><\/b><\/p><p class=\"small-body\"><i>Devi fare ci\u00f2 che \u00e8 etico e legale, indipendentemente dalle circostanze. Ricorda che la nostra redditivit\u00e0 a lungo termine dipende dalla nostra reputazione di operare con integrit\u00e0 ogni giorno e in ogni situazione. Se non sei sicuro di come procedere, fatti avanti e condividi le tue preoccupazioni. Contatta il tuo manager di linea o una delle risorse indicate nel nostro Codice. Parlare non \u00e8 mai facile, ma \u00e8 sempre la cosa giusta da fare<\/i>.<\/p><h3> <\/h3><h3 class=\"body-large\">Fare domande e segnalare problemi &#8211; SpeakUp<\/h3><p class=\"small-body\">Le violazioni note o sospette del nostro Codice, delle nostre politiche o della legge, o le domande sulla giusta linea d&#8217;azione, devono essere rivolte al tuo manager di riferimento. Se non ti senti a tuo agio a parlare con il tuo manager di riferimento, ci sono altre risorse disponibili per aiutarti: <\/p><ul><li class=\"small-body\">Contatta l&#8217;ufficio risorse umane.<\/li><li class=\"small-body\">Contatta l&#8217;ufficio legale e di conformit\u00e0<i>.<\/i><\/li><li class=\"small-body\">Contatta SpeakUp<i> (<\/i><a href=\"https:\/\/univers.speakup.report\/compliance\"><i>https:\/\/univers.speakup.report\/compliance<\/i><\/a><i>)<\/i> e i dettagli sono riportati nella Policy di SpeakUp.<\/li><\/ul><div> <\/div><h3 class=\"body-large\"><i style=\"color: var( --e-global-color-primary ); font-size: 18px; letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">Nessuna ritorsione<\/i><\/h3><p class=\"small-body\">Non tollereremo alcuna ritorsione nei confronti di un individuo che, in buona fede, faccia domande o denunci azioni che potrebbero essere in contrasto con il nostro Codice, le nostre politiche o la legge, o che contribuisca a un&#8217;indagine su una sospetta violazione.<\/p><p class=\"small-body\">Segnalare &#8220;in buona fede&#8221; significa fare un tentativo genuino di fornire informazioni oneste, complete e accurate, anche se poi si rivelano infondate o sbagliate.<\/p><p class=\"small-body\"><i> <\/i><i style=\"color: var( --e-global-color-primary ); letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\"> <\/i><\/p><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Il mio manager di riferimento mi ha ordinato di fare qualcosa che viola il nostro Codice. So che dovrei dirlo a qualcuno, ma ho paura che il mio responsabile di linea lo scopra e mi renda il lavoro difficile se lo faccio. <\/i><\/b><\/p><p class=\"small-body\"><i>Nessuno, incluso il tuo manager di riferimento, ha l&#8217;autorit\u00e0 di farti fare qualcosa che possa violare il nostro Codice o le politiche aziendali. Condividi il tuo problema con l&#8217;ufficio Risorse Umane, l&#8217;ufficio Legale e di Conformit\u00e0 o contatta SpeakUp: avrai la certezza di aver fatto la cosa giusta, che stiamo esaminando la situazione e che non saranno tollerate ritorsioni da parte del tuo manager di linea o di altri.  <\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><h3 class=\"body-large\">Collaborare con le indagini e le revisioni contabili<\/h3><p class=\"small-body\">Di tanto in tanto, potrebbe esserti chiesto di partecipare alle indagini e agli audit interni ed esterni che conduciamo. Ciascuno di noi \u00e8 tenuto a collaborare pienamente a queste richieste e a fornire informazioni veritiere, accurate e complete. <\/p><p class=\"small-body\">Potresti anche ricevere indagini o richieste da parte di funzionari governativi. Se vieni a conoscenza di una potenziale indagine o inchiesta governativa, avvisa immediatamente il tuo manager di linea e l&#8217;ufficio legale e di conformit\u00e0 prima di intraprendere o promettere qualsiasi azione. Se ti chiediamo di rispondere a una richiesta di un funzionario governativo, offri lo stesso livello di collaborazione e assicurati che le informazioni fornite siano veritiere, accurate e complete.  <\/p><p class=\"small-body\">Dobbiamo fare attenzione a non distruggere, alterare o nascondere alcun documento in previsione o in risposta a una richiesta di documenti e a non fornire o tentare di influenzare altri a fornire dichiarazioni incomplete, false o fuorvianti a un&#8217;azienda o a un investigatore governativo.<\/p><p class=\"small-body\"> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1435d8 elementor-widget elementor-widget-text-editor\" data-id=\"d1435d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>3. CI RISPETTIAMO A VICENDA<\/b><\/h2><h3 class=\"body-large\">Diversit\u00e0, equit\u00e0 e inclusione<\/h3><div> <\/div><p class=\"small-body\">Crediamo che l&#8217;ampia variet\u00e0 di background, competenze e culture dei nostri dipendenti sia alla base dei nostri risultati. Celebriamo la nostra diversit\u00e0, valorizziamo i contributi di ogni individuo e promuoviamo una cultura di inclusione. <\/p><p class=\"small-body\">Rispettiamo i nostri colleghi, i candidati e le terze parti e ci impegniamo a garantire che si sentano accolti e valorizzati e che abbiano l&#8217;opportunit\u00e0 di crescere, contribuire e svilupparsi con noi. Sosteniamo le leggi che vietano la discriminazione e offriamo pari opportunit\u00e0 di impiego, di reddito e di avanzamento in tutti i nostri dipartimenti, programmi, uffici e cantieri. <\/p><p class=\"small-body\"><b>Promuoviamo la diversit\u00e0<\/b><\/p><p class=\"small-body\">Le decisioni in materia di assunzione si basano esclusivamente sulle qualifiche, sulle competenze e sui risultati dimostrati, mai su razza, etnia, colore, religione, sesso (compresi gravidanza, orientamento sessuale e identit\u00e0 di genere), origine nazionale, et\u00e0, stato civile, disabilit\u00e0, estrazione sociale, informazioni genetiche o qualsiasi altra caratteristica protetta dalle leggi vigenti.<\/p><p class=\"small-body\"><b> <\/b><\/p><p class=\"small-body\"><b>Fai la cosa giusta<\/b><\/p><ul><li class=\"small-body\">Sii rispettoso, cortese e professionale nelle tue comunicazioni.<\/li><li class=\"small-body\">Non discriminare gli altri sulla base di caratteristiche protette dalla legge o dalla politica aziendale.<\/li><\/ul><p class=\"small-body\"><b> <\/b><\/p><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Battute, commenti o scritti, anche nelle e-mail, nelle app di messaggistica, sui manifesti e su altri materiali, che altri potrebbero considerare offensivi.<\/li><li class=\"small-body\">Pregiudizio inappropriato &#8211; se gestisci gli altri, valuti e prendi decisioni sui tuoi dipendenti utilizzando standard oggettivi e quantificabili.<\/li><\/ul><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Ho sentito un collega usare un linguaggio offensivo riguardo alla razza di un candidato. Dovrei dire qualcosa? <\/i><\/b><\/p><p class=\"small-body\"><i>S\u00ec. Un linguaggio del genere non ha posto in Univers. Se ti senti a tuo agio, parla direttamente con il tuo collega per esprimere la tua preoccupazione. Se non ti senti a tuo agio, parlane con il tuo manager di linea o con l&#8217;ufficio Risorse Umane. Promuoviamo un ambiente di lavoro rispettoso &#8211; per tutti &#8211; in cui la diversit\u00e0 e l&#8217;inclusione sono valorizzate.    <\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><h3 class=\"body-large\">Un luogo di lavoro privo di molestie<\/h3><p class=\"small-body\">Crediamo nel diritto di ogni individuo a lavorare in un ambiente privo di intimidazioni, molestie (comprese quelle sessuali), bullismo e comportamenti abusivi. Non tolleriamo comportamenti verbali o fisici da parte di dipendenti che molestino un altro dipendente, interrompano le sue prestazioni lavorative o creino un ambiente di lavoro intimidatorio, offensivo, abusivo o ostile. <\/p><p class=\"small-body\"><b>Fai la cosa giusta<\/b><\/p><ul><li class=\"small-body\">Sostenere le politiche volte a creare un ambiente di lavoro sicuro, etico e professionale e avere il coraggio di parlare delle parole o delle azioni di altri che mettono a disagio un individuo.<\/li><li class=\"small-body\">Non visitare siti internet inappropriati e non mostrare immagini sessualmente esplicite o offensive.<\/li><li class=\"small-body\">Segnalare tutti gli episodi di molestie e intimidazioni che possono compromettere la nostra capacit\u00e0 di lavorare insieme e di essere produttivi.<\/li><li class=\"small-body\">Non partecipare o istigare pettegolezzi o diffondere voci negative o non veritiere sulla nostra azienda, su un collega, su un cliente o su una terza parte. Se hai domande o dubbi, rivolgiti al tuo manager di riferimento. <\/li><li class=\"small-body\">Evita qualsiasi altro comportamento che possa creare attrito o erodere la fiducia.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Molestie, compresi abusi verbali, intimidazioni fisiche, minacce, schernimenti, commenti minacciosi, telefonate oscene o stalking.<\/li><li class=\"small-body\">Molestie sessuali, che comprendono comportamenti verbali o fisici indesiderati di natura sessuale (come avance sessuali o richieste di favori sessuali).<\/li><li class=\"small-body\">La visualizzazione di immagini o altri materiali sessualmente espliciti o offensivi, battute o commenti sessuali o offensivi (espliciti o con allusioni) e il leering.<\/li><\/ul><div> <\/div><div> <\/div><h3 class=\"body-large\"><span style=\"color: inherit; font-family: inherit; font-size: 1.75rem; letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">Salute e sicurezza<\/span><\/h3><p class=\"small-body\">Ognuno di noi ha la responsabilit\u00e0 di agire in modo da proteggere se stesso e gli altri. Indipendentemente dal lavoro che svolgiamo o dal luogo in cui lo svolgiamo, contiamo gli uni sugli altri per promuovere attivamente un luogo di lavoro sicuro e sano e per segnalare qualsiasi situazione che possa rappresentare un rischio per la salute, la sicurezza o la protezione. <\/p><p class=\"small-body\">Crediamo inoltre che un luogo di lavoro sicuro sia quello in cui ognuno di noi d\u00e0 il meglio di s\u00e9 ogni giorno. Durante il lavoro o le attivit\u00e0 aziendali, non usiamo o possediamo &#8211; n\u00e9 siamo sotto l&#8217;effetto di &#8211; droghe illegali o di qualsiasi sostanza che possa danneggiare la nostra salute, la nostra sicurezza, la nostra produttivit\u00e0 o la reputazione di Univers.   <\/p><p class=\"small-body\"><b>Un luogo di lavoro senza violenza<\/b><\/p><p class=\"small-body\">La violenza di qualsiasi tipo non ha posto all&#8217;interno di Univers. Non tollereremo: <\/p><ul><li class=\"small-body\">Atti di vandalismo, incendio doloso, sabotaggio o altre attivit\u00e0 criminali.<\/li><li class=\"small-body\">Infliggere lesioni fisiche a un&#8217;altra persona.<\/li><li class=\"small-body\">Comportamento intimidatorio, minaccioso o ostile.<\/li><li class=\"small-body\">Portare armi da fuoco o altre armi all&#8217;interno della propriet\u00e0 dell&#8217;azienda, a meno che non vi sia un&#8217;autorizzazione in tal senso.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b style=\"color: var( --e-global-color-primary ); letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">Fai la cosa giusta<\/b><\/p><ul><li class=\"small-body\">Rispettare tutte le leggi e i regolamenti applicabili in materia di salute e sicurezza sul lavoro e seguire le norme e le pratiche in materia di salute, sicurezza e protezione che si applicano al tuo lavoro.<\/li><li class=\"small-body\">Mantieni le postazioni, i corridoi e gli altri spazi di lavoro liberi da potenziali pericoli.<\/li><li class=\"small-body\">Rispettare i nostri standard di sicurezza fisica, in particolare per quanto riguarda l&#8217;ingresso e l&#8217;uscita dalle nostre strutture e la scorta dei nostri visitatori.<\/li><li class=\"small-body\">Comunica immediatamente al tuo responsabile di linea qualsiasi situazione che possa rappresentare una minaccia per la salute, la sicurezza o la protezione.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Pratiche o condizioni di lavoro non sicure.<\/li><li class=\"small-body\">Noncuranza nell&#8217;applicazione degli standard di sicurezza, come le procedure di ingresso in ufficio e i protocolli delle password.<\/li><\/ul><div> <\/div><div> <\/div><h3 class=\"body-large\">Privacy dei dati<\/h3><p class=\"small-body\">Seguiamo le politiche aziendali e tutte le leggi e i regolamenti applicabili nella raccolta, nell&#8217;accesso, nell&#8217;utilizzo, nella conservazione, nella condivisione e nello smaltimento dei dati personali. Utilizziamo i dati personali &#8211; e li condividiamo con altri &#8211; solo se necessario per scopi commerciali legittimi. Possiamo controllare e monitorare periodicamente i sistemi informatici, i messaggi e i registri delle chiamate di propriet\u00e0 dell&#8217;Universit\u00e0 per motivi di sicurezza e per altri scopi aziendali, in linea con le leggi vigenti.  <\/p><p class=\"small-body\"><b>I dati personali includono &#8230;<\/b><\/p><p class=\"small-body\">Qualsiasi cosa che possa essere utilizzata per identificare qualcuno, direttamente o indirettamente, come nome, indirizzo e-mail, numero di telefono o numero di carta di credito.<\/p><p class=\"small-body\"><b>Fai <\/b><b>La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Rispettare e proteggere i dati personali degli altri.<\/li><li class=\"small-body\">Raccogliere, accedere, elaborare, conservare, condividere e smaltire i dati personali solo in linea con le leggi vigenti.<\/li><li class=\"small-body\">Distruggere o smaltire in modo sicuro le informazioni sensibili, in conformit\u00e0 con le nostre politiche.<\/li><li class=\"small-body\">Diffida dei servizi di hosting, collaborazione o cloud &#8220;gratuiti&#8221; o acquistati individualmente che potrebbero mettere a rischio i dati personali.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Non riuscire a distruggere o a smaltire in modo sicuro i dati personali.<\/li><li class=\"small-body\">Utilizzare servizi di hosting, collaborazione o cloud &#8220;gratuiti&#8221; o acquistati individualmente che potrebbero mettere a rischio le informazioni personali.<\/li><\/ul><div> <\/div><div> <\/div><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Ho ricevuto un&#8217;e-mail da un collega che non era destinata a me. Contiene un elenco di nomi di dipendenti, numeri di telefono e informazioni sulla valutazione delle prestazioni. Non voglio mettere nei guai nessuno, ma cosa devo fare?  <\/i><\/b><\/p><p class=\"small-body\"><i>Innanzitutto, non devi leggere le informazioni n\u00e9 condividerle con altri. Comunica al mittente che l&#8217;e-mail non \u00e8 stata inviata al destinatario previsto e poi elimina l&#8217;e-mail. In secondo luogo, segnala l&#8217;accaduto al tuo manager di riferimento e al dipartimento di <\/i><a href=\"mailto:dpo-office@envison-digital.com\"><i>Dipartimento Privacy e Conformit\u00e0 dei dati<\/i><\/a><i>in modo da poter intraprendere eventuali azioni correttive, se necessario, e da istruire il mittente affinch\u00e9 non si verifichi un incidente simile.<\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b08921 elementor-widget elementor-widget-text-editor\" data-id=\"7b08921\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>4. PROTEGGIAMO I NOSTRI BENI E LE NOSTRE INFORMAZIONI<\/b><\/h2><h2><span style=\"background-color: var( --e-global-color-ddd80fe ); color: inherit; font-family: inherit; font-size: 1.75rem; letter-spacing: -0.54px; text-align: var(--text-align);\">Informazioni riservate<\/span><\/h2><p class=\"small-body\">Le informazioni sono uno dei nostri beni pi\u00f9 preziosi. Per questo motivo, siamo attenti a mantenere al sicuro le informazioni riservate e la propriet\u00e0 intellettuale (&#8220;IP&#8221;), limitandone l&#8217;accesso e l&#8217;utilizzo a coloro che sono debitamente autorizzati, che hanno la necessit\u00e0 di conoscerle per svolgere il proprio lavoro e che le utilizzano solo per scopi aziendali legittimi. <\/p><p class=\"small-body\">La protezione dei nostri diritti di propriet\u00e0 intellettuale \u00e8 fondamentale per la nostra attivit\u00e0. Dobbiamo comunicare tempestivamente al management qualsiasi invenzione o altra propriet\u00e0 intellettuale creata durante il periodo di impiego presso Univers e contattare l&#8217;ufficio legale e di conformit\u00e0 per domande sulla portata dei nostri diritti di propriet\u00e0 intellettuale e sul modo in cui tali diritti si riferiscono ai prodotti o alla propriet\u00e0 intellettuale di un&#8217;altra azienda. <\/p><p class=\"small-body\">Dobbiamo ricordare che il nostro obbligo di proteggere le informazioni riservate e la propriet\u00e0 intellettuale continua anche se il nostro impiego presso Univers termina.<\/p><p class=\"small-body\">Non dobbiamo portare o conservare informazioni riservate da ex datori di lavoro o condividere o accettare tali informazioni riservate nel corso del lavoro presso Univers.<\/p><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"><b>La propriet\u00e0 intellettuale \u00e8 &#8230;<\/b><\/p><p class=\"small-body\">I pensieri, le idee e i processi creativi che stanno dietro a ci\u00f2 che realizziamo. Include: <\/p><ul><li class=\"small-body\">Innovazioni e design<\/li><li class=\"small-body\">Sistemi, software e tecnologia<\/li><li class=\"small-body\">Brevetti, segreti commerciali, marchi e diritti d&#8217;autore<\/li><li class=\"small-body\">Piani di marketing e liste di clienti<\/li><li class=\"small-body\">Iniziative aziendali (esistenti, pianificate, proposte o in via di sviluppo)<\/li><\/ul><p class=\"small-body\"><b> <\/b><\/p><p class=\"small-body\"><b>Le informazioni riservate sono &#8230;<\/b><\/p><p class=\"small-body\">Per informazioni riservate si intendono tutte le informazioni o i materiali non generalmente disponibili al pubblico che riguardano l&#8217;attivit\u00e0 di un&#8217;azienda, le attivit\u00e0 di ricerca e sviluppo, i clienti, i dipendenti o le terze parti. Esempi di informazioni riservate sono: <\/p><ul><li class=\"small-body\">Piani aziendali, strategici e di marketing<\/li><li class=\"small-body\">Prezzi o margini target<\/li><li class=\"small-body\">Termini e condizioni del contratto<\/li><li class=\"small-body\">Mappe di prodotto e programmi di ricerca e sviluppo<\/li><li class=\"small-body\">Iniziative strategiche<\/li><li class=\"small-body\">Elenchi di clienti<\/li><li class=\"small-body\">Segreti commerciali e altra propriet\u00e0 intellettuale<\/li><li class=\"small-body\">Metodi, know-how e tecniche<\/li><li class=\"small-body\">Sistemi, software e tecnologia<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai <\/b><b>La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Comunica tempestivamente alla direzione dell&#8217;azienda qualsiasi invenzione o altra propriet\u00e0 intellettuale che crei mentre sei alle dipendenze di Univers.<\/li><li class=\"small-body\">Etichetta correttamente le informazioni riservate per indicare come devono essere gestite, distribuite e distrutte.<\/li><li class=\"small-body\">Archivia o comunica le informazioni aziendali solo utilizzando i sistemi informatici Univers.<\/li><li class=\"small-body\">Non utilizzare, modificare o divulgare mai informazioni riservate sulla nostra azienda, sui nostri clienti o su Terzi senza un&#8217;esplicita autorizzazione o senza un appropriato accordo di non divulgazione.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Discutere di informazioni riservate in luoghi in cui altri potrebbero ascoltare, ad esempio nei ristoranti, negli ascensori, in aereo, sui mezzi pubblici e quando usi il telefono.<\/li><li class=\"small-body\">Invio di informazioni riservate tramite punti di accesso wireless non sicuri, a fax o stampanti non presidiati.<\/li><li class=\"small-body\">Utilizzare informazioni riservate di altre parti che potrebbero essere proprietarie o soggette a restrizioni di divulgazione.<\/li><\/ul><div> <\/div><div> <\/div><h3 class=\"body-large\">Salvaguardia del patrimonio universitario  <\/h3><p class=\"small-body\">Ognuno di noi \u00e8 personalmente responsabile di essere un buon amministratore dei beni aziendali, utilizzandoli in modo responsabile e salvaguardandoli da frodi, sprechi e abusi. Rispettiamo tutte le politiche e le procedure di sicurezza delle informazioni, utilizziamo e gestiamo correttamente i beni di Univers. L&#8217;uso personale dei beni aziendali \u00e8 sconsigliato ma, laddove consentito, deve essere ridotto al minimo, non deve avere effetti negativi sulla produttivit\u00e0, sull&#8217;ambiente di lavoro o sulla nostra reputazione e non deve essere utilizzato per scopi esterni al lavoro o per guadagno personale.  <\/p><p class=\"small-body\">Tutte le informazioni create, condivise o scaricate sui sistemi aziendali appartengono a Univers e abbiamo il diritto di controllare e monitorare l&#8217;uso del sistema in qualsiasi momento, senza fornire alcuna notifica, nella misura consentita dalla legge.<\/p><p class=\"small-body\"><b>Beni fisici ed elettronici<\/b><\/p><p class=\"small-body\">I beni aziendali sono le risorse (materiali e immateriali) di propriet\u00e0 di Univers e messe a tua disposizione per svolgere il tuo lavoro. I beni fisici comprendono le strutture, i materiali e le attrezzature di Univers. I beni elettronici comprendono i sistemi informatici e di comunicazione, il software e l&#8217;hardware. Anche i file e i registri sono beni aziendali e abbiamo la responsabilit\u00e0 di garantirne la riservatezza, la sicurezza e l&#8217;integrit\u00e0.   <\/p><p class=\"small-body\"><b>Fai <\/b><b>La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Usa i beni dell&#8217;azienda per svolgere il tuo lavoro, mai per qualcosa di improprio o illegale.<\/li><li class=\"small-body\">Mantenere buone pratiche di sicurezza fisica.<\/li><li class=\"small-body\">Osservare le migliori pratiche di cybersecurity e privacy dei dati per proteggere le nostre risorse elettroniche:<\/li><li class=\"small-body\">Utilizza solo software che hanno ottenuto una licenza adeguata. Per sapere se un determinato uso del software \u00e8 autorizzato o meno, rivolgiti al reparto IT e al reparto Cybersecurity. <\/li><li class=\"small-body\">Fai attenzione ai tentativi di phishing: fai attenzione ad aprire allegati di e-mail provenienti da mittenti sconosciuti o a cliccare su link sospetti. Non condividere le password e non permettere ad altre persone, compresi amici e familiari, di utilizzare le risorse dell&#8217;Universit\u00e0. <\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Utilizzo dei beni dell&#8217;Universit\u00e0 senza autorizzazione o approvazione.<\/li><li class=\"small-body\">Uso eccessivo dei beni aziendali per scopi personali.<\/li><li class=\"small-body\">Violazioni della sicurezza fisica: fai attenzione e segnala qualsiasi persona che si trovi nelle nostre strutture e che non abbia le credenziali adeguate.<\/li><li class=\"small-body\">Copiare o utilizzare software senza licenza o &#8220;pirata&#8221; sui computer aziendali o su altre apparecchiature per svolgere le attivit\u00e0 aziendali: questa pratica potrebbe mettere a rischio i nostri sistemi ed \u00e8 severamente vietata.<\/li><li class=\"small-body\">Visualizzare o inviare materiali inappropriati utilizzando le risorse di Univers.<\/li><\/ul><div> <\/div><div> <\/div><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Posso trasferire informazioni aziendali, che includono dati personali, da Sharepoint a una chiavetta di memoria in modo da poter lavorare sulle informazioni quando sono lontano dall&#8217;ufficio. \u00c8 consentito? <\/i><\/b><\/p><p class=\"small-body\"><i>No. Consulta il dipartimento di Cybersecurity per ricevere assistenza e indicazioni. <\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"><b> <\/b><\/p><h3 class=\"body-large\">Media e comunicazioni<\/h3><p class=\"small-body\">Ci impegniamo a mantenere comunicazioni oneste, professionali e legali e a rispettare l&#8217;obbligo di fornire informazioni complete, corrette e tempestive in tutti i rapporti e documenti che descrivono la nostra attivit\u00e0 e i risultati finanziari. Abbiamo autorizzato determinati dipendenti a parlare a nostro nome per garantire che le informazioni sulla nostra azienda siano accurate e coerenti. Ognuno di noi deve aiutare l&#8217;azienda a garantire che solo le persone autorizzate parlino a nome di Univers.  <\/p><p class=\"small-body\"><b>Fai<\/b><b> La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Riferisci al reparto Marketing qualsiasi comunicazione proveniente da media, investitori, analisti azionari e membri della comunit\u00e0 finanziaria.<\/li><li class=\"small-body\">Chiedi l&#8217;approvazione del tuo manager di linea e dell&#8217;ufficio marketing prima di accettare di tenere discorsi pubblici, partecipare a gruppi di discussione o scrivere articoli per riviste professionali o altre comunicazioni pubbliche che riguardano l&#8217;Universit\u00e0.<\/li><li class=\"small-body\">Fai attenzione a ci\u00f2 che pubblichi sui social media. Non pubblicare mai contenuti irrispettosi, molesti o discriminatori in nessuna delle tue comunicazioni. <\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">La tentazione di utilizzare il tuo titolo o la tua affiliazione al di fuori del tuo lavoro per l&#8217;Universit\u00e0 senza che sia chiaro che l&#8217;uso \u00e8 solo a scopo identificativo.<\/li><li class=\"small-body\">Inviti a parlare &#8220;in via ufficiosa&#8221; con giornalisti o analisti che ti chiedono informazioni su Univers o sui suoi clienti o su Terzi.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>I social media<\/b><\/p><p class=\"small-body\">Fai attenzione quando scrivi comunicazioni che potrebbero essere pubblicate online, poich\u00e9 queste potrebbero riflettersi su di te o su Univers. Devi quindi prestare attenzione a ci\u00f2 che pubblichi sui tuoi social media. Se partecipi a gruppi di discussione su internet, chat room, bacheche, blog, siti di social media o altre comunicazioni elettroniche, anche con uno pseudonimo, non dare mai l&#8217;impressione di parlare a nome di Univers.  <\/p><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Ho letto un articolo online che riportava informazioni inesatte sulla nostra azienda. Posso rispondere nella sezione commenti per correggere queste informazioni errate? <\/i><\/b><\/p><p class=\"small-body\"><i>Se ritieni che sia stata pubblicata una dichiarazione falsa sulla nostra azienda, non commentare n\u00e9 rispondere, anche se il tuo intento \u00e8 quello di &#8220;mettere le cose in chiaro&#8221;. Il tuo post potrebbe essere interpretato in modo errato, dare adito a false voci o risultare impreciso o fuorviante. Contatta invece l&#8217;ufficio marketing in merito all&#8217;articolo e permetti loro di rispondere a nome della nostra azienda.  <\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c81b94e elementor-widget elementor-widget-text-editor\" data-id=\"c81b94e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"header-1\"><b>5.<\/b><b>   <\/b><b>RISPETTIAMO LE LEGGI VIGENTI<\/b><\/h2><h3 class=\"body-large\">Corruzione<\/h3><p class=\"small-body\">Ci impegniamo a rispettare tutte le leggi anticorruzione applicabili. Qualsiasi forma di concussione e corruzione non sar\u00e0 quindi tollerata, compresi i pagamenti agevolati (noti anche come &#8220;pagamenti a pioggia&#8221;) e le &#8220;tangenti&#8221;. A sostegno dei nostri sforzi per prevenire la corruzione, controlliamo e monitoriamo le Terze Parti che lavorano per nostro conto per assicurarci che operino in stretta conformit\u00e0 con i nostri standard e la legge e che mantengano registri accurati di tutte le transazioni.  <\/p><p class=\"small-body\"><b>Fai <\/b><b>La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Tieni presente che una tangente pu\u00f2 essere qualcosa di diverso dal denaro contante (inclusi contanti o carte regalo, buoni regalo e azioni): la corruzione consiste nel dare o ricevere qualsiasi cosa di valore (o nell&#8217;offrirsi di farlo) al fine di ottenere un vantaggio commerciale, contrattuale, normativo o personale.<\/li><li class=\"small-body\">Su una base sensibile al rischio (cio\u00e8 proporzionata al livello di rischio di corruzione), conduci un livello adeguato di due diligence sulle potenziali Terze Parti e nelle situazioni in cui le &#8220;bandiere rosse&#8221; indicherebbero la necessit\u00e0 di ulteriori controlli.<\/li><li class=\"small-body\">Non dare mai nulla di valore che non sia conforme alle leggi e ai regolamenti locali. Offri e accetta solo regali e intrattenimenti conformi alle nostre politiche e registra in modo accurato e completo tutti i pagamenti a terzi. <\/li><li class=\"small-body\">Evita di offrire regali o intrattenimenti quando il loro momento potrebbe essere visto come un tentativo di influenzare o ricompensare un risultato. Ad esempio, quando sta per essere presa la decisione di assegnare un contratto nell&#8217;ambito di una gara pubblica per la quale abbiamo presentato un&#8217;offerta. <\/li><\/ul><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Pagamenti di facilitazione o &#8220;untuosi&#8221; &#8211; piccoli pagamenti effettuati a un funzionario governativo di basso livello con lo scopo di incoraggiare il funzionario ad adempiere alle proprie responsabilit\u00e0.<\/li><li class=\"small-body\">Gli agenti che non desiderano che tutti i termini del loro impegno con Univers siano chiaramente documentati per iscritto.<\/li><li class=\"small-body\">Sappi che le regole su ci\u00f2 che possiamo dare o accettare dai funzionari governativi sono molto pi\u00f9 rigide.<\/li><li class=\"small-body\">Nel caso in cui un regalo o un&#8217;offerta di ospitalit\u00e0 superi la soglia prevista dalla nostra Politica Anticorruzione, prima di fare o ricevere tale regalo o offerta, dovrai ottenere l&#8217;approvazione preventiva e registrarlo tramite il nostro Registro G&amp;H.<\/li><\/ul><p class=\"small-body\"><b> <\/b><\/p><p class=\"small-body\"><b>Funzionari governativi<\/b><\/p><p class=\"small-body\">I funzionari governativi comprendono i dipendenti pubblici, i partiti politici, i candidati alle cariche, i dipendenti di organizzazioni pubbliche e le entit\u00e0 di propriet\u00e0 del governo.<\/p><p class=\"small-body\"> <\/p><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Durante un viaggio, ho ricevuto un regalo da un partner commerciale che ritengo eccessivo. Cosa dovrei fare? <\/i><\/b><\/p><p class=\"small-body\"><i>Prima di ricevere l&#8217;omaggio, devi chiedere consiglio al tuo (i) responsabile di funzione o di business; (ii) manager di linea; o (iii) proprietario del centro di costo. In caso di ulteriori dubbi, tutte le domande devono essere rivolte all&#8217;Ufficio Legale e Compliance. Potremmo dover restituire l&#8217;omaggio con una lettera che spiega la nostra politica. Se un regalo \u00e8 deperibile o non \u00e8 possibile restituirlo, un&#8217;altra opzione pu\u00f2 essere quella di distribuirlo ai dipendenti o donarlo in beneficenza, con una lettera di spiegazione al donatore.      <\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><h3>Anti-concorrenza\/Antitrust e concorrenza leale<\/h3><p class=\"small-body\">Crediamo che tutti traggano beneficio da un mercato fiorente. Ci impegniamo per una concorrenza libera e aperta. Non ci impegniamo in pratiche che possano limitare la concorrenza o cercare di ottenere vantaggi competitivi attraverso pratiche commerciali non etiche o illegali. Le leggi e i regolamenti anticoncorrenza\/antitrust sono complessi e, se violati, possono comportare multe salate sia per l&#8217;azienda che per i suoi dipendenti. Per questo motivo, \u00e8 bene che tu chieda aiuto per capire cosa sia appropriato e cosa no.    <\/p><p class=\"small-body\"><span style=\"background-color: var( --e-global-color-ddd80fe ); color: var( --e-global-color-primary ); letter-spacing: -0.54px; text-align: var(--text-align);\">Nella raccolta di informazioni commerciali sui nostri concorrenti, osserviamo i pi\u00f9 alti standard etici. Otteniamo informazioni sulla concorrenza solo attraverso mezzi legali ed etici, mai attraverso false dichiarazioni, frodi, inganni o l&#8217;uso di tecnologie per &#8220;spiare&#8221; gli altri. La condivisione di informazioni sensibili sulla concorrenza con i concorrenti (sia che tali informazioni appartengano a noi o a Terze Parti) \u00e8 sempre vietata.  <\/span><\/p><p class=\"small-body\"><b>Fai<\/b><b> La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Non intraprendere conversazioni con i concorrenti su informazioni sensibili dal punto di vista della concorrenza e non stipulare accordi con i concorrenti o con altri per mettere in atto comportamenti anticoncorrenziali.<\/li><li class=\"small-body\">Fai attenzione quando accetti informazioni sulla concorrenza da terze parti. Devi conoscere e fidarti delle loro fonti ed essere sicuro che le informazioni che ti forniscono non siano protette da leggi sul segreto commerciale, accordi di non divulgazione o di riservatezza. <\/li><li class=\"small-body\">Rispettare l&#8217;obbligo degli altri di mantenere riservate le informazioni sulla concorrenza, compresi gli ex dipendenti dei concorrenti.<\/li><li class=\"small-body\">Non interferire ingiustamente con le relazioni esistenti tra i nostri concorrenti e i loro clienti.<\/li><\/ul><div> <\/div><p class=\"small-body\"> <b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Comportamenti anticoncorrenziali, tra cui:<\/li><li class=\"small-body\">Manipolazione delle offerte &#8211; quando i concorrenti o i fornitori di servizi manipolano le offerte in modo da limitare la concorrenza leale. Ci\u00f2 pu\u00f2 includere la comparazione delle offerte, l&#8217;accordo di non fare offerte o la presentazione consapevole di offerte non competitive. <\/li><li class=\"small-body\">Collusione &#8211; quando le aziende comunicano o si accordano segretamente su come competere. Ci\u00f2 potrebbe includere accordi o scambi di informazioni su prezzi, condizioni, salari o allocazione di clienti, fornitori o mercati. <\/li><li class=\"small-body\">Legame &#8211; quando un&#8217;azienda con potere di mercato costringe i clienti ad accettare servizi o prodotti che non vogliono o di cui non hanno bisogno.<\/li><li class=\"small-body\">Prezzi predatori &#8211; quando un&#8217;azienda con potere di mercato vende un servizio sottocosto per eliminare o danneggiare un concorrente, con l&#8217;intento di recuperare la perdita di entrate in un secondo momento aumentando i prezzi dopo che il concorrente \u00e8 stato eliminato o danneggiato.<\/li><li class=\"small-body\">Portare con s\u00e9 documenti o documenti informatici di precedenti datori di lavoro in violazione di leggi o contratti.<\/li><li class=\"small-body\">Utilizzare informazioni riservate di altri senza le dovute approvazioni.<\/li><li class=\"small-body\">Usare i colloqui di lavoro per raccogliere informazioni riservate su concorrenti o altri.<\/li><li class=\"small-body\">Suggerimenti da parte di terzi per nuovi prodotti, caratteristiche del prodotto o servizi quando la fonte dell&#8217;idea originale non \u00e8 del tutto nota.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Di recente ho sentito parlare di una riunione che un concorrente terr\u00e0 in occasione di una conferenza a cui parteciper\u00f2. Non credo che mi permetteranno di partecipare se sapranno che vengo dall&#8217;Universit\u00e0. Posso partecipare a condizione di mantenere segreta la mia identit\u00e0?  <\/i><\/b><\/p><p class=\"small-body\"><i>No. Raccogliere informazioni sui concorrenti \u00e8 un&#8217;attivit\u00e0 commerciale legittima se fatta nel modo giusto. Nascondere &#8211; o non rivelare &#8211; la propria identit\u00e0 non \u00e8 <\/i><b><i>non<\/i><\/b><i> il modo giusto. E la tua partecipazione a un evento di un concorrente potrebbe addirittura sollevare problemi di antitrust. Mantieni sempre standard elevati e assicurati di evitare anche solo l&#8217;apparenza di qualcosa di improprio.<\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><h3 class=\"body-large\">Insider Trading<\/h3><p class=\"small-body\">Rispettiamo le leggi sull&#8217;insider trading. Chiunque in Univers pu\u00f2 venire a conoscenza di informazioni materiali non pubbliche (&#8220;interne&#8221;) sulla nostra azienda o su altre societ\u00e0 quotate in borsa, ma non usiamo queste informazioni n\u00e9 le divulghiamo ad altri affinch\u00e9 possano fare trading (una pratica nota come &#8220;tipping&#8221;). Se vieni a conoscenza di informazioni interne, non devi agire in base ad esse fino a quando le informazioni non sono state rese pubbliche. La mancata osservanza di questo divieto potrebbe esporre te e Univers a sanzioni civili e penali.   <\/p><p class=\"small-body\"><b>Le informazioni materiali sono &#8230;<\/b><\/p><p class=\"small-body\">Informazioni che un investitore ragionevole prenderebbe in considerazione per decidere se acquistare o vendere un titolo, ad esempio informazioni su:<\/p><ul><li class=\"small-body\">Un significativo sviluppo del prodotto<\/li><li class=\"small-body\">L&#8217;acquisizione o la perdita di un cliente, di un fornitore o di un contratto importante, una proposta di fusione, un&#8217;acquisizione o una cessione.<\/li><li class=\"small-body\">Un&#8217;espansione o una riduzione significativa delle operazioni<\/li><li class=\"small-body\">Proiezioni di utili o perdite future<\/li><li class=\"small-body\">Avvio o risoluzione di cause legali<\/li><li class=\"small-body\">Cambiamenti importanti nella gestione o nel controllo<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai<\/b><b> La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Rispetta il diritto di ogni azienda di proteggere le proprie informazioni interne.<\/li><li class=\"small-body\">Non acquistare o vendere mai titoli di una societ\u00e0 quando sei in possesso di informazioni privilegiate su di essa.<\/li><li class=\"small-body\">Proteggere le informazioni materiali non pubbliche dal pubblico in generale, comprese le informazioni in formato elettronico e cartaceo.<\/li><li class=\"small-body\">Discuti qualsiasi domanda o dubbio sull&#8217;insider trading con il tuo manager di linea o con l&#8217;ufficio legale e di conformit\u00e0.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Richieste da parte di amici o parenti di informazioni su aziende con cui facciamo affari o su cui abbiamo informazioni riservate: anche le conversazioni occasionali potrebbero essere considerate come &#8220;soffiate&#8221; illegali di informazioni interne.<\/li><li class=\"small-body\">Condividere informazioni materiali non pubbliche con chiunque, sia di proposito che per caso, a meno che non sia essenziale per le attivit\u00e0 dell&#8217;Universit\u00e0.<\/li><\/ul><div> <\/div><div> <\/div><div> <\/div><h3>Conformit\u00e0 al commercio globale<\/h3><p class=\"small-body\">Abbiamo operazioni globali che supportano una base di clienti in tutto il mondo. Per mantenere e far crescere la nostra attivit\u00e0, rispettiamo rigorosamente tutte le leggi e i regolamenti applicabili che: <\/p><ul><li class=\"small-body\">Governare l&#8217;importazione, l&#8217;esportazione e la riesportazione dei nostri prodotti, della tecnologia e del software.<\/li><li class=\"small-body\">Imporre embarghi commerciali e sanzioni economiche che vietano alcune o tutte le attivit\u00e0 commerciali con determinati Paesi e i loro cittadini, o con specifiche entit\u00e0 o individui.<\/li><li class=\"small-body\">Proibire i boicottaggi non sanzionati o il rifiuto di commerciare con un determinato paese.<\/li><\/ul><p class=\"small-body\">Ogni persona di Univers che ha la responsabilit\u00e0 di esportare prodotti o di ricevere prodotti importati ha la responsabilit\u00e0 di controllare i clienti, i fornitori e le transazioni per garantire la conformit\u00e0 a tutti i requisiti applicabili.<\/p><p class=\"small-body\"><b style=\"color: var( --e-global-color-primary ); letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">Fai la cosa giusta<\/b><\/p><ul><li class=\"small-body\">Tieni presente che qualsiasi violazione delle leggi sull&#8217;importazione o sull&#8217;esportazione, anche per ignoranza, potrebbe avere effetti dannosi e duraturi sulla nostra attivit\u00e0.<\/li><li class=\"small-body\">Ottenere tutte le licenze necessarie prima di esportare o riesportare prodotti, servizi o tecnologie.<\/li><li class=\"small-body\">Riportare informazioni complete, accurate e dettagliate su ogni prodotto importato, compresi il luogo o i luoghi di produzione e il costo totale.<\/li><li class=\"small-body\">Rivolgi qualsiasi domanda relativa alle importazioni o alle esportazioni dei nostri prodotti, parti o tecnologie all&#8217;ufficio legale e di conformit\u00e0.<\/li><\/ul><div> <\/div><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Trasporto di beni aziendali che contengono determinate tecnologie (come un computer che un socio porta con s\u00e9 durante un viaggio di lavoro) in un altro paese.<\/li><li class=\"small-body\">Trasferire dati tecnici e tecnologia a qualcuno in un altro paese, ad esempio tramite e-mail, conversazioni, riunioni o accesso a database. Questa restrizione si applica alla condivisione di informazioni con colleghi e non dipendenti. <\/li><\/ul><div> <\/div><div> <\/div><p class=\"small-body\"> <\/p><h3 class=\"body-large\">Antiriciclaggio<\/h3><p class=\"small-body\">Ci impegniamo a condurre le nostre attivit\u00e0 in modo da prevenire il riciclaggio di denaro e a rispettare tutte le leggi contro il riciclaggio di denaro e il finanziamento del terrorismo ovunque operiamo. Segnala qualsiasi transazione e attivit\u00e0 finanziaria sospetta al tuo manager di riferimento, all&#8217;ufficio finanziario, al direttore legale o al consulente per la regolamentazione e la conformit\u00e0. Puoi anche fare una segnalazione anonima tramite la piattaforma di segnalazione SpeakUp.  <\/p><p class=\"small-body\"><b>Il riciclaggio di denaro \u00e8 &#8230;<\/b><\/p><p class=\"small-body\">Il processo per far apparire &#8220;pulito&#8221; (o legittimo) il &#8220;denaro sporco&#8221; (i proventi di attivit\u00e0 criminali) nascondendo i benefici derivanti da una condotta criminale in modo che sembrino provenire da una fonte legittima. Si tratta di un problema globale che pu\u00f2 minare l&#8217;integrit\u00e0 di un&#8217;azienda, danneggiarne la reputazione ed esporre sia l&#8217;azienda che gli individui coinvolti a pesanti sanzioni. <\/p><p class=\"small-body\"><b>Fai attenzione a<\/b><\/p><ul><li class=\"small-body\">Un cliente o una Terza Parte che si rifiuta di fornire documenti di identificazione o i documenti di identificazione forniti non sono ufficiali o sembrano essere falsi o altrimenti manomessi.<\/li><li class=\"small-body\">Pagamenti a o da individui o aziende che non hanno alcun legame apparente o logico con il cliente, con la Terza Parte o con la transazione.<\/li><li class=\"small-body\">Pagamenti verso o da paesi considerati ad alto rischio di riciclaggio di denaro o di finanziamento del terrorismo.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22c3110 elementor-widget elementor-widget-text-editor\" data-id=\"22c3110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-family: 'Scto Grotesk A', sans-serif; color: #1e1e1e; letter-spacing: -0.54px;\"><span style=\"font-weight: bold; color: inherit; font-family: inherit; font-size: 2rem; letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">6.<\/span><span style=\"font-weight: bold; color: inherit; font-family: inherit; font-size: 2rem; letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">   <\/span><span style=\"font-weight: bold; color: inherit; font-family: inherit; font-size: 2rem; letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">CONDUCIAMO GLI AFFARI IN MODO RESPONSABILE<\/span><\/h2><h3 style=\"font-family: 'Scto Grotesk A', sans-serif; color: #1e1e1e; letter-spacing: -0.54px;\">Registrazione accurata e completa<\/h3><div style=\"letter-spacing: -0.54px;\"> <\/div><p style=\"letter-spacing: -0.54px;\">L&#8217;accurata tenuta dei registri non \u00e8 compito di una sola persona, di un solo team o di un solo reparto. Alcuni dipendenti hanno responsabilit\u00e0 particolari in questo ambito, ma tutti noi contribuiamo al processo di registrazione dei risultati aziendali o alla tenuta dei registri. <\/p><p style=\"letter-spacing: -0.54px;\">Abbiamo la responsabilit\u00e0 di assicurarci che le informazioni registrate siano accurate, tempestive e complete, oltre che mantenute e smaltite in modo coerente con i nostri controlli interni, i requisiti di divulgazione e gli obblighi legali. I nostri libri e registri devono riflettere in modo accurato ed equo le nostre transazioni in modo sufficientemente dettagliato e in conformit\u00e0 con le nostre pratiche e politiche contabili. <span style=\"font-weight: bold;\"> <\/span><\/p><p style=\"letter-spacing: -0.54px;\"> <\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Fai la cosa giusta<\/span><\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Sii guidato dai principi di trasparenza e veridicit\u00e0, creando documenti aziendali che riflettano accuratamente la verit\u00e0 dell&#8217;evento o della transazione sottostante.<\/li><li style=\"font-size: 18px;\">Non nascondere mai un illecito o permettere ad altri di farlo, e non nascondere o distruggere mai i documenti in risposta a &#8211; o in previsione di &#8211; un&#8217;indagine o un audit.<\/li><li style=\"font-size: 18px;\">Rivolgi le tue domande o i tuoi dubbi sulla conservazione o la distruzione dei documenti aziendali al <a href=\"mailto:dpo-office@envison-digital.com\">dipartimento Data Privacy &amp; Compliance<\/a>.<\/li><li style=\"font-size: 18px;\">Rispettare il nostro processo di governance dei contratti e il nostro sistema di controlli finanziari, operativi e di conformit\u00e0, compreso l&#8217;ottenimento delle opportune approvazioni per le decisioni finanziarie e commerciali, che costituiscono la base della nostra autorit\u00e0 di agire per conto di Univers.<\/li><\/ul><div> <\/div><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Fai attenzione a<\/span><\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Registrazioni che non sono chiare e complete o che nascondono la vera natura di un&#8217;azione.<\/li><li style=\"font-size: 18px;\">Fondi, attivit\u00e0 o passivit\u00e0 non dichiarate o non registrate.<\/li><li style=\"font-size: 18px;\">Distruzione impropria di documenti.<\/li><\/ul><div> <\/div><div style=\"letter-spacing: -0.54px;\"> <\/div><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\"><i>DOMANDE E RISPOSTE<\/i><\/span><\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\"><i>Stiamo sforando il budget per un piccolo contratto e il nostro project manager mi ha chiesto di spendere parte del mio tempo su quel contratto per un altro progetto separato. Non mi sembra giusto. <\/i><\/span><\/p><p style=\"letter-spacing: -0.54px;\"><i>Non \u00e8 giusto. Fare ci\u00f2 che il tuo <\/i><i>collega<\/i><i> ti chiede sarebbe falsificare un record ed \u00e8 severamente vietato dalle nostre politiche. Hai l&#8217;obbligo di applicare il tuo tempo in modo accurato al progetto corretto. Spiega al project manager che non hai intenzione di soddisfare la sua richiesta e perch\u00e9, e poi segnala la situazione al tuo manager di linea o a un&#8217;altra risorsa in modo che la situazione possa essere affrontata in modo appropriato.<\/i><\/p><p style=\"letter-spacing: -0.54px;\"><i> <\/i><\/p><p style=\"letter-spacing: -0.54px;\"><i> <\/i><\/p><p style=\"letter-spacing: -0.54px;\"> <\/p><h3 style=\"font-family: 'Scto Grotesk A', sans-serif; color: #1e1e1e; letter-spacing: -0.54px;\"><span style=\"font-size: 1.75rem; letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">Fair Dealing<\/span><\/h3><p style=\"letter-spacing: -0.54px;\">Sappiamo che il successo della nostra azienda dipende dalla costruzione di relazioni e dal mantenimento della fiducia. Trattiamo i nostri clienti, i concorrenti e le terze parti in modo equo, come vorremmo essere trattati noi. Siamo reattivi alle richieste e alle domande e lavoriamo per capire e soddisfare le loro esigenze. Cerchiamo di ottenere un vantaggio competitivo attraverso le nostre eccezionali soluzioni software, i nostri servizi e il nostro supporto, mai attraverso pratiche non etiche o illegali.   <\/p><p style=\"letter-spacing: -0.54px;\"> <\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Fai la cosa giusta<\/span><\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Dite la verit\u00e0 sulla nostra azienda, sulle nostre offerte e sulle nostre capacit\u00e0: non fate mai affermazioni che non siano vere.<\/li><li style=\"font-size: 18px;\">Non manipolare, occultare, travisare fatti materiali, abusare di informazioni privilegiate o intraprendere qualsiasi altra pratica commerciale sleale.<\/li><li style=\"font-size: 18px;\">Se noti o sospetti un errore, un&#8217;omissione, un ritardo ingiustificato o un difetto nella qualit\u00e0 o nel servizio clienti, parlane con il tuo responsabile di linea.<\/li><\/ul><div style=\"letter-spacing: -0.54px;\"> <\/div><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Fai attenzione a<\/span><\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Pressioni da parte di un collega o di una terza parte per ridurre gli standard di qualit\u00e0 o di consegna.<\/li><li style=\"font-size: 18px;\">Richieste da parte di un cliente o di una terza parte di fare qualcosa che tu consideri non etico o illegale.<\/li><li style=\"font-size: 18px;\">L&#8217;overpromising, ovvero la tentazione di dire ai clienti ci\u00f2 che si pensa vogliano sentire, invece di dire loro la verit\u00e0.<\/li><\/ul><div> <\/div><div style=\"letter-spacing: -0.54px;\"> <\/div><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\"><i>DOMANDE E RISPOSTE<\/i><\/span><\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\"><i>Mentre facevamo brainstorming su alcune nuove idee per il marketing del nostro software, uno dei miei colleghi ci ha suggerito di inserire un&#8217;affermazione secondo cui il prodotto di un concorrente non rispetta i nostri stessi standard. \u00c8 un&#8217;affermazione che sospettiamo sia vera, ma non abbiamo prove certe. \u00c8 corretto includere questa affermazione nel nostro annuncio?  <\/i><\/span><\/p><p style=\"letter-spacing: -0.54px;\"><i>Ci sono alcuni tipi di affermazioni che possiamo fare sui prodotti dei nostri concorrenti, ma solo se tali affermazioni sono veritiere e accurate e se possiamo supportarle con una solida documentazione. <\/i><\/p><p style=\"letter-spacing: -0.54px;\"><i> <\/i><\/p><h3 style=\"font-family: 'Scto Grotesk A', sans-serif; color: #1e1e1e; letter-spacing: -0.54px;\">Le nostre attivit\u00e0 governative<\/h3><p style=\"letter-spacing: -0.54px;\">In quanto azienda che partecipa al settore degli appalti pubblici, lavoriamo per essere un partner valido e responsabile. Ci impegniamo a soddisfare i numerosi requisiti legali, normativi e contrattuali che si applicano ai nostri contratti governativi. Tali requisiti possono riguardare le gare d&#8217;appalto, l&#8217;esecuzione del contratto, i regali e gli intrattenimenti, gli acquisti, la contabilit\u00e0, le fatture, i subappalti, le pratiche di assunzione e altre questioni.  <\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Fai la cosa giusta<\/span><\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Se sei responsabile della conduzione di affari con il governo per conto di Univers, assicurati di conoscere e rispettare i requisiti contrattuali e tutte le leggi e i regolamenti che si applicano al nostro lavoro con il governo.<\/li><li style=\"font-size: 18px;\">Tieni presente che molti dei requisiti che dobbiamo soddisfare si estendono anche ai singoli e alle aziende che lavorano per nostro conto.<\/li><\/ul><div style=\"letter-spacing: -0.54px;\"> <\/div><div style=\"letter-spacing: -0.54px;\"> <\/div><h3 style=\"font-family: 'Scto Grotesk A', sans-serif; color: #1e1e1e; letter-spacing: -0.54px;\">Conflitti di interesse<\/h3><p style=\"letter-spacing: -0.54px;\">Abbiamo la responsabilit\u00e0 di prendere decisioni aziendali che siano nel migliore interesse di Univers e di usare il buon senso nel farlo. Interessi o relazioni personali che influenzano o che potrebbero ragionevolmente sembrare influenzare qualsiasi decisione che prendi per conto di Univers potrebbero danneggiare la nostra reputazione e la nostra attivit\u00e0. Anche se un conflitto di interessi non \u00e8 necessariamente un problema di per s\u00e9, devi rivelare immediatamente un conflitto di interessi reale, potenziale o percepito per proteggere te stesso e Univers e ogni volta che l&#8217;azienda lo richiede.  <\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Un conflitto di interessi pu\u00f2 verificarsi quando &#8230;<\/span><\/p><p style=\"letter-spacing: -0.54px;\">Hai un interesse o un&#8217;attivit\u00e0 concorrente che potrebbe interferire o sembrare interferire con la tua capacit\u00e0 di agire nel migliore interesse di Univers e con i suoi doveri verso Univers.<\/p><p style=\"letter-spacing: -0.54px;\">Esempi di aree in cui spesso si verificano conflitti di interesse sono:<\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Relazioni familiari o personali<\/li><li style=\"font-size: 18px;\">Lavoro esterno<\/li><li style=\"font-size: 18px;\">Opportunit\u00e0 aziendali<\/li><li style=\"font-size: 18px;\">Interessi finanziari personali<\/li><li style=\"font-size: 18px;\">Servire come membro del consiglio di amministrazione o di un comitato consultivo<\/li><\/ul><div style=\"letter-spacing: -0.54px;\"> <\/div><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Fare <\/span><span style=\"font-weight: bold;\">La cosa giusta<\/span><\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Prendere decisioni commerciali nell&#8217;interesse di Univers.<\/li><li style=\"font-size: 18px;\">Evitare situazioni di conflitto di interessi reali, potenziali e percepite, quando possibile.<\/li><li style=\"font-size: 18px;\">Affronta in modo proattivo le situazioni che potrebbero mettere i tuoi interessi o quelli di un tuo familiare in potenziale conflitto con quelli di Univers.<\/li><li style=\"font-size: 18px;\">Divulgare qualsiasi situazione che sia, o che possa essere percepita come, un conflitto di interessi in conformit\u00e0 con la nostra Politica sul conflitto di interessi e sull&#8217;insider trading.<\/li><li style=\"font-size: 18px;\">Se non sei sicuro di trovarti in una posizione di conflitto, consulta l&#8217;ufficio Risorse Umane.<\/li><\/ul><div> <\/div><div> <\/div><div style=\"letter-spacing: -0.54px;\"> <\/div><h3 style=\"font-family: 'Scto Grotesk A', sans-serif; color: #1e1e1e; letter-spacing: -0.54px;\">Regali e intrattenimento<\/h3><p style=\"letter-spacing: -0.54px;\">Sappiamo che offrire e accettare doni, pasti e ospitalit\u00e0 pu\u00f2 creare buoni rapporti di lavoro, ma le offerte sontuose (eccessive o stravaganti) o date\/accettate con troppa frequenza possono inviare un messaggio sbagliato, compromettere la nostra obiettivit\u00e0 e rappresentare un conflitto di interessi. Offriamo e accettiamo solo regali e intrattenimenti conformi alle nostre politiche e alle leggi e normative vigenti e ci assicuriamo che tutto ci\u00f2 che viene offerto o ricevuto sia accuratamente riportato nei nostri libri e registri. <\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Fai <\/span><span style=\"font-weight: bold;\">La cosa giusta<\/span><\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Non chiedere o sollecitare regali, favori, intrattenimenti o servizi personali.<\/li><li style=\"font-size: 18px;\">Assicurati che i regali e gli intrattenimenti siano offerti per costruire relazioni commerciali, non per influenzare il processo decisionale.<\/li><li style=\"font-size: 18px;\">Non offrire mai regali a &#8211; o accettarli da &#8211; una Terza Parte con cui sei coinvolto in trattative contrattuali.<\/li><li style=\"font-size: 18px;\">Prima di offrire o fornire regali o intrattenimenti, \u00e8 necessario rispettare non solo le nostre politiche, ma anche quelle dell&#8217;organizzazione del destinatario.<\/li><li style=\"font-size: 18px;\">Non offrire o accettare mai regali o intrattenimenti, anche se conformi alle nostre politiche, se l&#8217;intento \u00e8 quello di influenzare impropriamente una decisione.<\/li><li style=\"font-size: 18px;\">Se sospetti che un collega o una terza parte stia cercando di influenzare in modo improprio un cliente o un funzionario pubblico, condividi immediatamente la tua preoccupazione.<\/li><li style=\"font-size: 18px;\">Ottenere l&#8217;approvazione attraverso il nostro Registro dei regali e dell&#8217;ospitalit\u00e0 online prima di offrire regali e\/o ospitalit\u00e0 che soddisfino le soglie di segnalazione stabilite nella nostra Politica anticorruzione.<\/li><\/ul><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\"> <\/span><\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Fai attenzione a<\/span><\/p><ul style=\"font-size: 18px; background-color: #f5f5f5; letter-spacing: -0.54px;\"><li style=\"font-size: 18px;\">Regali in contanti o equivalenti: non sono mai accettabili.<\/li><li style=\"font-size: 18px;\">Situazioni che potrebbero mettere in imbarazzo te o la nostra azienda (ad esempio, intrattenimento in locali a sfondo sessuale).<\/li><li style=\"font-size: 18px;\">I divieti e le restrizioni in materia di doni e ospitalit\u00e0 specifici per ogni Paese che possono essere indicati nella nostra Politica Anticorruzione.<\/li><\/ul><div style=\"letter-spacing: -0.54px;\"> <\/div><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\"><i>DOMANDE E RISPOSTE<\/i><\/span><\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\"><i>Uno dei nostri fornitori mi ha inviato una carta regalo. Cosa devo fare? <\/i><\/span><\/p><p style=\"letter-spacing: -0.54px;\"><i>Una carta regalo \u00e8 un equivalente in denaro e non \u00e8 mai consentita. Devi restituire la carta regalo spiegando gentilmente che la nostra politica ti vieta di tenerla. <\/i><\/p><p style=\"letter-spacing: -0.54px;\"><i> <\/i><\/p><p style=\"letter-spacing: -0.54px;\"><i> <\/i><\/p><h3 style=\"font-family: 'Scto Grotesk A', sans-serif; color: #1e1e1e; letter-spacing: -0.54px;\">Lavorare con i nostri clienti, fornitori e partner<\/h3><p style=\"letter-spacing: -0.54px;\">I nostri clienti e le terze parti sono parte integrante del nostro successo. Cerchiamo terze parti che condividano il nostro impegno verso standard elevati e prendiamo decisioni di approvvigionamento basate su criteri oggettivi, valutando la loro integrit\u00e0 e la capacit\u00e0 di soddisfare le nostre esigenze e i nostri requisiti commerciali e tecnici. Tutti gli accordi sono negoziati in buona fede e devono essere equi e ragionevoli per entrambe le parti.  <span style=\"font-weight: bold; color: var( --e-global-color-primary ); letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\"> <\/span><\/p><p style=\"letter-spacing: -0.54px;\"><span style=\"font-weight: bold;\">Minerali di conflitto<\/span><\/p><h2><span style=\"letter-spacing: -0.54px; color: var( --e-global-color-primary ); font-size: 18px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">I ricavi derivanti dai minerali dei conflitti sono stati collegati al finanziamento di gruppi impegnati in violenze estreme e atrocit\u00e0 dei diritti umani. Lavoriamo a stretto contatto con i fornitori di materie prime, parti e componenti e comunichiamo la nostra aspettativa che i fornitori e i venditori rispettino tutte le leggi applicabili, comprese quelle volte a fornire minerali privi di conflitti.   <\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36c0cb3 elementor-widget elementor-widget-text-editor\" data-id=\"36c0cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"header-1\"><b style=\"color: inherit; font-family: inherit; letter-spacing: -0.54px; text-align: var(--text-align); font-size: 2rem; background-color: var( --e-global-color-ddd80fe );\">7.<\/b><b style=\"color: inherit; font-family: inherit; letter-spacing: -0.54px; text-align: var(--text-align); font-size: 2rem; background-color: var( --e-global-color-ddd80fe );\">   <\/b><b style=\"color: inherit; font-family: inherit; letter-spacing: -0.54px; text-align: var(--text-align); font-size: 2rem; background-color: var( --e-global-color-ddd80fe );\">FACCIAMO LA DIFFERENZA NEL MONDO<\/b><\/h2><h3 class=\"body-large\">Sostenibilit\u00e0 e gestione ambientale<\/h3><p class=\"small-body\">Stiamo compiendo progressi misurabili verso il net zero e tutto ci\u00f2 che verr\u00e0 dopo. Ci impegniamo ad aiutare i nostri partner a ottimizzare i sistemi energetici e a ridurre le emissioni di anidride carbonica, e ci dedichiamo anche a un&#8217;azione aggressiva per il clima nelle nostre operazioni e in tutta la nostra catena di valore. Rispettiamo tutte le leggi, i regolamenti e i permessi in materia di ambiente, salute e sicurezza. Contatta il Responsabile ESG per qualsiasi domanda sulla conformit\u00e0 o sui requisiti di reporting associati alle leggi e alle politiche in materia di ambiente, salute e sicurezza.   <\/p><p class=\"small-body\"><b>Fai <\/b><b>La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Affrontare il cambiamento climatico migliorando l&#8217;efficienza delle risorse e riducendo l&#8217;impatto ambientale per ottenere una riduzione delle emissioni di gas serra per le nostre attivit\u00e0, i nostri clienti, i nostri partner e la nostra catena di fornitura.<\/li><li class=\"small-body\">Promuovere lo sviluppo e l&#8217;utilizzo di energie rinnovabili per ridurre la dipendenza da fonti non rinnovabili.<\/li><li class=\"small-body\">Sostenere l&#8217;uso responsabile delle risorse integrando la Politica degli Acquisti Verdi nel nostro processo di acquisto.<\/li><li class=\"small-body\">Puntiamo a trasformare l&#8217;economia in un&#8217;economia circolare e a basse emissioni di carbonio attraverso i nostri prodotti e servizi.<\/li><li class=\"small-body\">Ridurre al minimo gli impatti negativi che le nostre attivit\u00e0 possono avere sull&#8217;ambiente naturale nell&#8217;ambito della salute dell&#8217;ecosistema e della biodiversit\u00e0.<\/li><li class=\"small-body\">Cercare in modo proattivo le opportunit\u00e0 per i nostri dipendenti, partner e clienti di ridurre al minimo l&#8217;impronta di carbonio, i rifiuti, l&#8217;energia e l&#8217;uso di risorse naturali nelle nostre operazioni e nella nostra catena del valore.<\/li><\/ul><div> <\/div><div> <\/div><p class=\"small-body\"><b> <\/b><span style=\"background-color: var( --e-global-color-ddd80fe ); color: inherit; font-family: inherit; font-size: 1.75rem; letter-spacing: -0.54px; text-align: var(--text-align);\">Qualit\u00e0 e sicurezza dei prodotti<\/span><\/p><p class=\"small-body\">Durante l&#8217;intero ciclo di vita del prodotto e la consegna del progetto, ci assicuriamo che i nostri processi e le nostre procedure relative ai prodotti e ai servizi soddisfino o superino i nostri standard di qualit\u00e0, sicurezza e prestazioni, nonch\u00e9 gli standard stabiliti dalle leggi, dalle normative governative e dal nostro settore. Ci aspettiamo lo stesso livello di impegno da parte delle nostre Terze Parti. <\/p><p class=\"small-body\"><b>Fai la cosa giusta<\/b><\/p><ul><li class=\"small-body\">Fai la tua parte per garantire test di qualit\u00e0 e rapporti sulle prestazioni completi e accurati.<\/li><li class=\"small-body\">Onorare il nostro impegno per la qualit\u00e0 &#8211; lavorare per un miglioramento continuo, ma non prendere mai scorciatoie o fare eccezioni che potrebbero compromettere la qualit\u00e0 o la sicurezza dei nostri prodotti e servizi.<\/li><li class=\"small-body\">Se ritieni che ci sia un problema o un difetto che potrebbe compromettere le nostre offerte, segnalalo immediatamente al tuo manager di linea o al dipartimento di Garanzia della Qualit\u00e0.<\/li><\/ul><div> <\/div><div> <\/div><h3 class=\"body-large\">Diritti umani<\/h3><p class=\"small-body\">Crediamo che la dignit\u00e0 umana inizi dalle nostre interazioni quotidiane tra di noi, con i nostri terzi e con i nostri clienti. Ci\u00f2 significa promuovere la diversit\u00e0 e fare la nostra parte per proteggere i diritti e la dignit\u00e0 di tutti coloro con cui facciamo affari. Conduciamo le nostre attivit\u00e0 in modo da rispettare i diritti umani e la dignit\u00e0 di tutti e sosteniamo gli sforzi internazionali per promuovere e proteggere i diritti umani, compresa l&#8217;assoluta opposizione alla schiavit\u00f9 e al traffico di esseri umani.  <\/p><p class=\"small-body\"><b>Fai <\/b><b>La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Lavorare per coinvolgere terze parti che si impegnano a rispettare pratiche di lavoro eque e standard umani sul posto di lavoro.<\/li><li class=\"small-body\">Sii vigile: segnala qualsiasi sospetto o prova di abusi dei diritti umani, come il lavoro forzato o la tratta di esseri umani, nelle nostre attivit\u00e0 o in quelle di terzi.<\/li><\/ul><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Ho sentito dire che una delle terze parti che stiamo prendendo in considerazione ha la reputazione di essere coinvolta in pratiche di lavoro discutibili. Devo dirlo a qualcuno? <\/i><\/b><\/p><p class=\"small-body\"><i>Anche se non sei stato coinvolto nel processo decisionale relativo a questa Terza Parte, \u00e8 importante che tu condivida ci\u00f2 che hai sentito con i colleghi responsabili della decisione. Ogni volta che vieni a conoscenza di un&#8217;attivit\u00e0 che va contro le nostre politiche o che potrebbe riflettersi negativamente sulla nostra azienda, contiamo su di te per far sentire la tua voce. <\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"><i> <\/i><\/p><p class=\"small-body\"> <\/p><h3 class=\"body-large\">Attivit\u00e0 politiche<\/h3><p class=\"small-body\">Ognuno di noi ha il diritto di partecipare volontariamente al processo politico contribuendo con il proprio tempo e le proprie risorse a sostegno di campagne o candidati. Tuttavia, devi sempre chiarire che le tue opinioni e azioni personali non sono quelle di Univers e non devi mai utilizzare i fondi, il tempo, le strutture o il nome di Univers per scopi politici senza un&#8217;adeguata autorizzazione. <\/p><p class=\"small-body\"><b>Fai<\/b><b> La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Assicurati che le tue opinioni e attivit\u00e0 politiche personali non siano considerate come quelle dell&#8217;azienda.<\/li><li class=\"small-body\">Seguire tutte le leggi, le norme e i regolamenti elettorali federali, statali, locali e stranieri in materia di contributi e spese.<\/li><li class=\"small-body\">Non esercitare mai pressioni dirette o indirette su un altro dipendente affinch\u00e9 contribuisca, sostenga o si opponga a qualsiasi candidato o partito politico.<\/li><li class=\"small-body\">Discutere e coordinarsi in anticipo con l&#8217;Ufficio Legale e di Conformit\u00e0 prima di intraprendere qualsiasi interazione che possa essere considerata un&#8217;attivit\u00e0 di lobbying.<\/li><li class=\"small-body\">Evita anche solo l&#8217;apparenza di versare contributi politici o di beneficenza per ottenere favori o nel tentativo di esercitare un&#8217;influenza impropria.<\/li><li class=\"small-body\">Rispettare le leggi anticoncussione e corruzione e la nostra Politica anticoncussione e corruzione.<\/li><\/ul><p class=\"small-body\"> <\/p><p class=\"small-body\"><b><i>DOMANDE E RISPOSTE<\/i><\/b><\/p><p class=\"small-body\"><b><i>Una mia amica si candida per una carica politica. Posso aiutare la sua campagna elettorale? <\/i><\/b><\/p><p class=\"small-body\"><i>S\u00ec, puoi sostenere il tuo amico a livello personale. Assicurati per\u00f2 che la tua partecipazione avvenga al di fuori dell&#8217;orario di lavoro e non utilizzare beni, strutture, fondi o il nome dell&#8217;Universit\u00e0 per sostenere la campagna. <\/i><\/p><p class=\"small-body\"><b> <\/b><\/p><h3 class=\"body-large\">Connettersi con le nostre comunit\u00e0<\/h3><p class=\"small-body\">Crediamo nell&#8217;impegno responsabile in attivit\u00e0 caritatevoli e filantropiche per avere un impatto positivo sulle comunit\u00e0 in cui viviamo e lavoriamo. Come azienda, contribuiamo con fondi, tempo e talento a sostenere programmi aziendali e cause locali. Ognuno di noi \u00e8 incoraggiato &#8211; ma non obbligato &#8211; a partecipare alle numerose iniziative che Univers sostiene.  <\/p><p class=\"small-body\"><b>Fai <\/b><b>La cosa giusta<\/b><\/p><ul><li class=\"small-body\">Ritenere le nostre Terze Parti responsabili &#8211; assicurarci che operino in modo etico, nel rispetto della legge e in modo coerente con il nostro Codice, le nostre politiche e i nostri valori.<\/li><li class=\"small-body\">Ricorda che anche i nostri clienti e le terze parti ripongono la loro fiducia in noi. Comprendi e rispetta le loro aspettative in merito alla protezione, all&#8217;uso e alla divulgazione delle informazioni riservate che ci forniscono. <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1281c89 elementor-widget elementor-widget-text-editor\" data-id=\"1281c89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ultima modifica: 14 set 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1135249153\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1135249153\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-1541cee e-con-full e-flex e-con e-child\" data-id=\"1541cee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8eac6b elementor-widget elementor-widget-text-editor\" data-id=\"e8eac6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><strong>1. INTRODUZIONE<\/strong><\/h2><p class=\"small-body\">La presente Politica di SpeakUp (la &#8220;<strong>Politica<\/strong>&#8220;) si applica a tutte le societ\u00e0 del gruppo Univers (il &#8220;<strong>Gruppo<\/strong>&#8220;), pertanto quando ci riferiamo a &#8220;Univers&#8221;, &#8220;societ\u00e0&#8221; &#8220;noi&#8221;, &#8220;ci&#8221; o &#8220;nostro&#8221;, intendiamo la societ\u00e0 o le societ\u00e0 pertinenti del gruppo Univers.<\/p><p class=\"small-body\">La presente Politica si applica a tutti i membri di Univers, quali dipendenti (a tempo pieno e parziale), lavoratori a contratto, consulenti, funzionari e amministratori del Gruppo (collettivamente indicati come<strong>&#8220;Persone Universitarie<\/strong>&#8221; o &#8220;tu&#8221;).<\/p><p class=\"small-body\">Univers si riserva il diritto di rivedere, rivedere, modificare o sostituire la Politica e\/o di introdurre nuove politiche o linee guida a integrazione della presente Politica di volta in volta per riflettere le mutevoli esigenze dell&#8217;azienda e, ove necessario, per riflettere variazioni locali, requisiti aggiuntivi e\/o eccezioni alla presente Politica. Sar\u00e0 responsabilit\u00e0 di ogni Persona Universitaria conoscere e rispettare la versione pi\u00f9 aggiornata di questa Politica. <\/p><p class=\"small-body\">Univers si impegna ad adottare pratiche commerciali responsabili e a condurre sempre le proprie attivit\u00e0 e operazioni con integrit\u00e0 e in modo onesto ed etico. \u00c8 essenziale che tutte le Persone Univers, i clienti, le terze parti e le comunit\u00e0 in cui operiamo siano in grado di segnalare preoccupazioni relative a comportamenti illegali, sospetti o reali, a comportamenti non etici o a comportamenti scorretti nella nostra attivit\u00e0. <\/p><p class=\"small-body\">Se le domande e le preoccupazioni pi\u00f9 autentiche vengono portate alla nostra attenzione attraverso i nostri canali di comunicazione, ci consentiranno di individuare tempestivamente i potenziali problemi. Questo ci permette di ridurre al minimo i danni potenziali per la nostra Universit\u00e0, i nostri clienti, gli investitori, i colleghi e i partner commerciali. <\/p><p class=\"small-body\">Univers \u00e8 quindi determinata a creare e mantenere una cultura in cui le domande possano essere poste e le segnalazioni di comportamenti non etici o illegali o di violazioni del nostro Codice di Condotta, delle nostre politiche e dei nostri processi, possano essere fatte attraverso i nostri vari canali di segnalazione senza timore o minaccia di ritorsioni, e che le segnalazioni siano trattate in modo serio, confidenziale, equo e in conformit\u00e0 alle leggi e ai regolamenti applicabili. Questo impegno \u00e8 sottoscritto dal nostro top management e dai direttori di Univers come parte del loro sostegno individuale e collettivo al nostro Codice di Condotta. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92fa308 elementor-widget elementor-widget-text-editor\" data-id=\"92fa308\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"header-1\"><strong>2. PRINCIPI GENERALI<\/strong><\/h2><h6 class=\"body-large\"><strong>A. QUANDO FARE DOMANDE O SEGNALARE I TUOI DUBBI<\/strong><\/h6><p class=\"small-body\">Ogni Persona Univers ha il dovere di segnalare una violazione delle leggi e dei regolamenti applicabili, del nostro Codice di Condotta, delle politiche e dei processi associati, o un comportamento non in linea con i nostri valori quando tale comportamento si verifica all&#8217;interno della nostra azienda o coinvolge qualsiasi persona con cui siamo in affari. Rimanere in silenzio in queste situazioni pu\u00f2 causare danni gravi o irreparabili alla nostra azienda e\/o alle persone interessate da tali comportamenti. <\/p><p class=\"small-body\">Dovresti fare domande anche se non sei sicuro che un particolare comportamento o una linea d&#8217;azione pianificata sia legale o etica, o se desideri una guida sulla legalit\u00e0 o l&#8217;etica di una particolare questione legata al lavoro.<br><br><\/p><h6 class=\"body-large\"><strong>B. DI QUALI ARGOMENTI PUOI PARLARE?<\/strong><\/h6><p class=\"small-body\">Devi segnalare preoccupazioni e\/o chiedere consigli o indicazioni su azioni o comportamenti che violano le leggi e i regolamenti vigenti, i valori di Univers, il Codice di Condotta e le politiche e i processi aziendali. Tali questioni possono includere :- <\/p><ul><li class=\"small-body\">Questioni finanziarie come insider trading, frodi, dichiarazioni finanziarie errate, riciclaggio di denaro, finanziamento del terrorismo, appropriazione indebita, furto o imbroglio.<\/li><li class=\"small-body\">Abuso di alcol o droghe<\/li><li class=\"small-body\">Corruzione<\/li><li class=\"small-body\">Questioni relative a violazioni dei diritti umani e del diritto del lavoro, tra cui discriminazione sul posto di lavoro, molestie (anche sessuali), abuso di potere, abuso, mobbing o licenziamento ingiusto.<\/li><li class=\"small-body\">Questioni ambientali e di salute e sicurezza (ad esempio se hai subito un infortunio sul lavoro)<\/li><li class=\"small-body\">Conflitto di interessi<\/li><li class=\"small-body\">Controlli sulle esportazioni e violazioni delle sanzioni commerciali<\/li><li class=\"small-body\">Uso improprio o violazione della propriet\u00e0 intellettuale e\/o delle informazioni confidenziali<\/li><li class=\"small-body\">Protezione dei dati, privacy o criminalit\u00e0 informatica<\/li><li class=\"small-body\">Furto, danneggiamento o uso improprio dei beni di Univers o di terzi in nostra custodia o controllo<\/li><li class=\"small-body\">Problemi di prodotto e di qualit\u00e0<\/li><li class=\"small-body\">Comportamento anticoncorrenziale \/ antitrust, sleale o non etico<\/li><li class=\"small-body\">Ritorsioni contro chiunque parli<\/li><li class=\"small-body\">falsificazione, distruzione o manomissione impropria di documenti e\/o informazioni rilevanti per Univers o per le sue operazioni commerciali.<\/li><\/ul><p><span style=\"letter-spacing: -0.54px;\"><br>T<\/span><span style=\"letter-spacing: -0.54px;\">La presente Politica non \u00e8 destinata a risolvere domande o reclami che potresti avere in merito alle tue condizioni di impiego (ad esempio, compensi, valutazioni delle prestazioni, sviluppo della carriera) o a risolvere questioni personali che potresti avere con i tuoi colleghi. In questi casi, devi rivolgerti all&#8217;ufficio Risorse Umane.<br><br><\/span><\/p><h6 class=\"body-large\"><strong>C. COME SEGNALARE I TUOI DUBBI<\/strong><\/h6><p class=\"small-body\">Se possibile, se sei preoccupato per un determinato comportamento, prendi in considerazione l&#8217;idea di parlare con la persona il cui comportamento ti preoccupa. Ad esempio, se una persona fa delle battute che trovi offensive o che ti mettono a disagio, potresti spiegare alla persona che fa le battute come ti senti. Tuttavia, se non ti senti a tuo agio, puoi utilizzare uno dei seguenti canali di segnalazione dell&#8217;Universit\u00e0. <\/p><p class=\"small-body\">Questi sono:-<\/p><ul><li class=\"small-body\">il tuo manager di riferimento;<\/li><li class=\"small-body\">il dipartimento delle risorse umane;<\/li><li class=\"small-body\">l&#8217;ufficio legale e di conformit\u00e0; e<\/li><li class=\"small-body\">la piattaforma &#8220;SpeakUp&#8221;.<\/li><\/ul><p class=\"small-body\">Come linea guida generale, la prima persona a cui rivolgersi per sollevare una questione interna \u00e8 il tuo responsabile di linea. Tuttavia, se non ti senti a tuo agio o se \u00e8 proprio il tuo manager di riferimento a voler sollevare un problema, puoi utilizzare gli altri canali di segnalazione disponibili in Univers. Per aiutarti a decidere a chi rivolgerti all&#8217;interno di Univers in caso di domande o di segnalazioni interne, consulta il diagramma di flusso riportato nell&#8217;allegato A.  <br><br><\/p><h6 class=\"small-body\"><strong>D. ABUSO DEI CANALI DI SEGNALAZIONE<\/strong><\/h6><p class=\"small-body\">Quando segnali un problema, le informazioni fornite possono portare a decisioni che hanno un impatto su altri. Pertanto, quando fai una segnalazione, devi sapere o ragionevolmente credere, nel momento in cui la fai, che le informazioni fornite siano vere. Una segnalazione fatta senza un&#8217;onesta convinzione della veridicit\u00e0 delle informazioni fornite o deliberatamente fuorviante sar\u00e0 considerata in malafede. Se fai una denuncia in malafede non sarai tutelato. Infatti, una segnalazione deliberatamente falsa o fuorviante rappresenter\u00e0 un uso improprio dei canali di segnalazione di problemi reali. Potranno essere intraprese azioni disciplinari nei confronti di chi abusa dei canali di segnalazione di preoccupazioni reali. Tuttavia, non ci saranno conseguenze negative per te se le tue preoccupazioni si rivelano infondate.      <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfed2fc elementor-widget elementor-widget-text-editor\" data-id=\"cfed2fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"header-1\"><strong>3. PORRE DOMANDE O SEGNALARE PROBLEMI TRAMITE LA PIATTAFORMA SPEAKUP<br><br><\/strong><\/h2><h6 class=\"body-large\"><strong>A. METODI PER ESPRIMERSI ATTRAVERSO LA PIATTAFORMA SPEAK UP<\/strong><\/h6><p class=\"small-body\">La piattaforma SpeakUp \u00e8 gestita da un fornitore di servizi indipendente ed \u00e8 disponibile 24 ore su 24, 7 giorni su 7, 365 giorni all&#8217;anno. Puoi fare domande o segnalare i tuoi dubbi nella tua lingua, per telefono o via internet. <\/p><p class=\"small-body\">Tutte le segnalazioni e le domande poste saranno prese in seria considerazione.<\/p><p class=\"small-body\">Puoi fare domande o sollevare dubbi<\/p><ul><li><b>Web<\/b>. Clicca su <a href=\"https:\/\/univers.speakup.report\/en-GB\/compliance\/home\">https:\/\/univers.speakup.report\/en-GB\/compliance\/home<\/a> che \u00e8 in inglese e scegli la lingua in cui vuoi fare il report. In alternativa, puoi cliccare sul seguente codice QR:-  <br><br><\/li><\/ul><p><img fetchpriority=\"high\" decoding=\"async\" id=\"11091370\" class=\"\" title=\"\" src=\"https:\/\/a.storyblok.com\/f\/223827\/356x320\/2a7b2d9af0\/speakup-webqr.png\" alt=\"\" width=\"236\" height=\"212\"><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a72437 elementor-widget elementor-widget-text-editor\" data-id=\"3a72437\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><b>Telefono<\/b>. I numeri di telefono specifici per ogni paese sono riportati nell&#8217;Allegato B. <\/li><li>L&#8217;<b>applicazione SpeakUp<\/b> si chiama &#8220;SpeakUp by People Intouch&#8221; dall&#8217;App Store\/Google Play e pu\u00f2 essere scaricata su un cellulare\/dispositivo mobile. Puoi cliccare sul seguente codice QR: &#8211; <br><br><\/li><\/ul><p><img decoding=\"async\" class=\"alignnone size-full wp-image-22705\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speakup.jpg\" alt=\"\" width=\"232\" height=\"228\" srcset=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speakup.jpg 232w, https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speakup-24x24.jpg 24w, https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speakup-48x48.jpg 48w\" sizes=\"(max-width: 232px) 100vw, 232px\" \/><\/p><p>Le istruzioni passo-passo su come utilizzare i diversi canali di accesso tramite SpeakUp sono contenute nell&#8217;Allegato B della presente Policy.<\/p><p><img decoding=\"async\" class=\"alignnone wp-image-22706\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speaup-platform-300x177.jpg\" alt=\"\" width=\"500\" height=\"295\" srcset=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speaup-platform-300x177.jpg 300w, https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speaup-platform.jpg 695w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p><p>Puoi anche visitare il portale Legal and Compliance per utilizzare i vari canali SpeakUp.<br><br><\/p><h6 class=\"body-large\"><strong>B. INFORMAZIONI DA FORNIRE QUANDO SI SEGNALA UN PROBLEMA<\/strong><\/h6><p class=\"small-body\">Se desideri segnalare un problema tramite la piattaforma SpeakUp, fornisci il maggior numero possibile di informazioni concrete. Questo permetter\u00e0 ai team che esamineranno e\/o indagheranno sul tuo problema di farlo in modo efficace. Le informazioni che dovresti fornire sono le seguenti  <\/p><ul><li class=\"small-body\">Il contesto, la storia e il motivo del rapporto;<\/li><li class=\"small-body\">I nomi, le date, i luoghi e altre informazioni rilevanti;<\/li><li class=\"small-body\">Documenti, foto, video o registrazioni vocali che possano supportare il tuo rapporto (possibile solo se il rapporto viene effettuato online e soggetto a limitazioni nella dimensione del file).<\/li><\/ul><p class=\"small-body\">Non \u00e8 necessario che tu sia in possesso di tutti i fatti relativi a un problema prima di fare una segnalazione. \u00c8 importante che tu non indaghi su un problema per raccogliere prove sufficienti a dimostrare che si \u00e8 verificata una violazione da segnalare. Questo compito dovrebbe essere affidato al Team investigativo (definito nella sezione 3C). Tuttavia, cerca di fornire informazioni ragionevolmente sufficienti per consentire al Team investigativo di effettuare almeno una valutazione preliminare sulla natura del tuo reclamo e sulle persone o entit\u00e0 coinvolte.   <br><br><\/p><h6 class=\"small-body\"><strong>C. COSA SUCCEDE DOPO AVER FATTO UNA DOMANDA O SOLLEVATO UN PROBLEMA TRAMITE LA PIATTAFORMA SPEAK UP?<br><br><\/strong><\/h6><p class=\"small-body\"><strong><i>Riconoscimento<\/i><\/strong><\/p><p class=\"small-body\">Dopo aver inviato una segnalazione o una domanda, la piattaforma SpeakUp confermer\u00e0 che il tuo messaggio \u00e8 stato ricevuto dal sistema.<br><br><\/p><p class=\"small-body\"><strong><i>Revisione iniziale<\/i><\/strong><\/p><p class=\"small-body\">Un Triage Team (la cui funzione principale \u00e8 quella di condurre una valutazione preliminare di alto livello di ogni messaggio ricevuto tramite la piattaforma SpeakUp per determinare questioni quali la natura di un&#8217;accusa che \u00e8 stata segnalata) condurr\u00e0 un esame iniziale della tua domanda o segnalazione. Il Team di Triage determiner\u00e0 inoltre la linea d&#8217;azione appropriata e assegner\u00e0 la segnalazione a una persona o a un team appropriato per rispondere alla tua domanda, esaminare ulteriormente il tuo problema e\/o condurre un&#8217;indagine (&#8220;Team investigativo&#8221;). <\/p><p class=\"small-body\">Riceverai inoltre una risposta dal Team di Triage o dal Team Investigativo entro 7 giorni dalla ricezione della tua segnalazione.<br><br><\/p><p class=\"small-body\"><strong><i>Rispondere alle domande, approfondire l&#8217;esame e\/o le indagini<\/i><\/strong><\/p><p class=\"small-body\">Se hai posto una domanda che non richiede ulteriori verifiche e\/o indagini, la tua domanda ricever\u00e0 una risposta nel pi\u00f9 breve tempo possibile. Se il tuo problema non rientra nell&#8217;ambito di applicazione di questa Politica, puoi anche rivolgerti direttamente al dipartimento competente. <\/p><p class=\"small-body\">Se hai fatto una segnalazione, il Team Investigativo stabilir\u00e0 se la tua segnalazione \u00e8 sufficientemente valida e potrebbe<\/p><ul><li class=\"small-body\">ti contattano per chiederti maggiori informazioni;<\/li><li class=\"small-body\">ti chiedono se sei disposto ad essere intervistato;<\/li><li class=\"small-body\">per quanto possibile, fornirti una stima del tempo necessario per trattare il tuo caso;<\/li><li class=\"small-body\">fornirti aggiornamenti regolari sull&#8217;andamento delle sue indagini, nella misura in cui sia legale o appropriato farlo; e\/o<\/li><li class=\"small-body\">proporre altri mezzi per risolvere il problema, ad esempio la mediazione.<\/li><\/ul><p class=\"small-body\">Le tempistiche di queste fasi dipendono da vari fattori, come la complessit\u00e0 e la natura del caso. Tuttavia, il Team Investigativo proceder\u00e0 senza ritardi irragionevoli per affrontare qualsiasi segnalazione. <\/p><p class=\"small-body\">Il Team Investigativo condurr\u00e0 ulteriori esami e\/o indagini principalmente attraverso verifiche a tavolino e, se necessario, interviste a testimoni.<br><br><\/p><p class=\"small-body\"><i style=\"color: var( --e-global-color-primary ); letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\"><b>Reporting<\/b><\/i><\/p><p class=\"small-body\">Una volta completata l&#8217;indagine, il team investigativo riferir\u00e0 i risultati e le raccomandazioni al responsabile dell&#8217;ufficio legale, normativo e di conformit\u00e0, che approver\u00e0, modificher\u00e0 o formuler\u00e0 le proprie raccomandazioni sulle misure da adottare da parte del dipartimento o dei dipartimenti Universitari competenti e\/o dell&#8217;azienda,<\/p><p class=\"small-body\">Verrai inoltre informato dell&#8217;esito dell&#8217;indagine, a meno che ci\u00f2 non violi le leggi vigenti, gli obblighi di riservatezza e\/o altri diritti di terzi. (\u00c8 importante ricordare che anche una persona accusata di illecito ha diritto alla riservatezza). <br><br><\/p><p class=\"small-body\"><i><b>Azioni<\/b><\/i><\/p><p class=\"small-body\">Il Team Investigativo si assicurer\u00e0 che le misure approvate, modificate o apportate dal Responsabile Legale e Regolamentare e dall&#8217;Ufficio Compliance siano eseguite dai dipartimenti Universitari e\/o dalla societ\u00e0 interessati.<br><br><\/p><p class=\"small-body\"><i><b>Rapporti e chiusura<\/b><\/i><\/p><p class=\"small-body\">Il team investigativo chiuder\u00e0 il caso dopo che le indagini e le misure raccomandate sono state eseguite.<\/p><p class=\"small-body\">Sarai avvisato una volta chiuso il caso, anche se non sarai informato dell&#8217;esito dell&#8217;indagine.<\/p><p class=\"small-body\">Tutte le questioni che rientrano nell&#8217;ambito di applicazione della presente Politica e che vengono presentate tramite la piattaforma SpeakUp saranno gestite secondo un protocollo di indagine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edac996 elementor-widget elementor-widget-text-editor\" data-id=\"edac996\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"small-body\"><strong>4. PROTEGGERE UNA PERSONA CHE SEGNALA UN PROBLEMA<\/strong><\/h2><p class=\"small-body\">Indipendentemente dai canali utilizzati per segnalare un problema internamente, i seguenti principi chiave sono applicati a chiunque segnali un problema attraverso uno qualsiasi dei nostri canali di segnalazione.<br><br><\/p><h6 class=\"body-large\"><strong>A. RISERVATEZZA<\/strong><\/h6><p class=\"small-body\">Qualsiasi segnalazione fatta dall&#8217;utente in conformit\u00e0 con la presente Politica sar\u00e0 trattata con la massima riservatezza. Le informazioni saranno condivise solo con un numero limitato di persone in base alla necessit\u00e0 di sapere. Le informazioni saranno condivise solo se richiesto dalla legge, se \u00e8 in gioco un importante interesse pubblico e\/o se \u00e8 assolutamente necessario per indagare correttamente sulla questione denunciata. In linea di principio, qualsiasi persona sotto indagine sar\u00e0 informata di essere oggetto di una segnalazione in corso di indagine il prima possibile, a meno che la notifica non possa compromettere l&#8217;indagine, violare la legge applicabile o se vi \u00e8 il rischio di ritorsioni nei confronti della persona che ha effettuato la segnalazione.   <\/p><p class=\"small-body\">A prescindere da tutte le misure adottate per proteggere la tua riservatezza, non si pu\u00f2 mai garantire che tu non venga coinvolto dalla persona sotto indagine. Univers ha inoltre il diritto di effettuare le divulgazioni necessarie per conformarsi alle leggi e ai regolamenti vigenti e\/o per richiedere una consulenza legale indipendente. <br><br><\/p><h6 class=\"small-body\"><strong>B. ANONIMATO<\/strong><\/h6><p class=\"small-body\">Sebbene sia possibile effettuare una segnalazione in forma anonima, \u00e8 preferibile rivelare la propria identit\u00e0 quando si effettua la segnalazione tramite SpeakUp, in modo che :-<\/p><ul><li class=\"small-body\">le tue preoccupazioni possono essere affrontate in modo pi\u00f9 efficiente. (Ad esempio, il team investigativo pu\u00f2 avere pi\u00f9 facilmente accesso a te e chiederti maggiori dettagli); <\/li><li class=\"small-body\">possiamo fornire una protezione pi\u00f9 efficace contro le ritorsioni, come richiesto dalle leggi e dai regolamenti applicabili (se \u00e8 probabile che tu ne subisca); e<\/li><li class=\"small-body\">qualsiasi sospetto che il rapporto sia stato fatto con cattiveria o in &#8220;malafede&#8221; pu\u00f2 essere evitato o minimizzato.<\/li><\/ul><div><br><br><\/div><h6><strong>C. PRIVACY DEI DATI<\/strong><\/h6><p><span style=\"color: var( --e-global-color-primary ); letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">I dati personali elaborati per rispondere alle segnalazioni saranno trattati da Univers in modo trasparente, equo, etico e legale. La nostra Politica sulla privacy e sulla protezione dei dati descrive i nostri requisiti minimi per il trattamento dei dati personali e per garantire il rispetto delle leggi e dei regolamenti applicabili in materia di protezione dei dati.   <\/span><\/p><p class=\"small-body\">Tali dati personali saranno mantenuti riservati e saranno utilizzati esclusivamente per gli scopi descritti nella presente Informativa e\/o per conformarsi alle leggi e ai regolamenti applicabili.  <\/p><p class=\"small-body\">I dati personali vengono elaborati nel nostro legittimo interesse per individuare comportamenti non etici e scorretti. Inoltre, i dati personali possono essere elaborati per consentirci di adempiere agli obblighi previsti dalle leggi e dai regolamenti applicabili che ci impongono di implementare processi e sistemi di whistleblowing. <\/p><p class=\"small-body\">Nel corso della segnalazione di un problema e\/o della risposta a una segnalazione, i dati personali saranno trasferiti all&#8217;estero (cio\u00e8 al di fuori del paese in cui viene effettuata la segnalazione).<\/p><p class=\"small-body\">Quando fai una segnalazione utilizzando la piattaforma SpeakUp, i dati personali forniti nella segnalazione saranno ospitati nei Paesi Bassi e in Francia. I traduttori utilizzati per le segnalazioni telefoniche non in lingua inglese sono situati in paesi con livelli adeguati di protezione dei dati. I dati personali possono anche essere condivisi con dipendenti autorizzati all&#8217;interno di Univers al fine di rispondere e gestire le segnalazioni effettuate ai sensi della presente Policy, di monitorare le segnalazioni e di avere la supervisione di questa Policy. Tali trasferimenti sono soggetti a garanzie adeguate per la protezione dei dati personali nei paesi terzi. Ove richiesto, i dati personali possono essere condivisi anche con terze parti, se necessario, per fornire supporto nella revisione e nella risposta alle segnalazioni effettuate ai sensi della presente Politica. Queste terze parti dispongono di misure tecniche e organizzative adeguate e sono stati o saranno stipulati con loro contratti per far rispettare i loro obblighi ai sensi delle leggi applicabili in materia di protezione dei dati.     <\/p><p class=\"small-body\">Se i tuoi dati personali vengono trattati in relazione a una segnalazione che effettui ai sensi della presente Policy, Univers ti tuteler\u00e0 in relazione ai tuoi dati personali come previsto dalle leggi sulla privacy applicabili. In genere ci\u00f2 include il diritto di essere informati, di accedere, di rettificare, di cancellare, di limitare il trattamento, di opporsi e di presentare un reclamo in relazione ai tuoi dati personali. Se fai una richiesta sui tuoi dati personali che ci fornisci quando fai una segnalazione o quando ti viene richiesto dai team di Triage e\/o di Investigazione, la tua richiesta verr\u00e0 esaminata caso per caso e ti verr\u00e0 data risposta in conformit\u00e0 con le politiche di Univers relative alla privacy e alla protezione dei dati.  <br><br><\/p><h6 class=\"body-large\"><strong>D. NON RITORSIONE<\/strong><\/h6><p class=\"body-large\">Nell&#8217;ambito del nostro impegno a rispettare le leggi e i regolamenti applicabili in materia di whistleblowing e a creare una cultura in cui tutte le Persone Universitarie si sentano a proprio agio nel parlare tempestivamente di comportamenti scorretti, non tolleriamo alcuna forma di ritorsione n\u00e9 permettiamo che vengano intraprese azioni negative nei confronti di chiunque semplicemente faccia domande, riferisca i propri dubbi in buona fede e\/o collabori a un&#8217;indagine o a un&#8217;inchiesta.<\/p><p class=\"small-body\">Le ritorsioni potrebbero assumere la forma di una qualsiasi delle seguenti azioni e non saranno tollerate \ud83d\ude42<\/p><ul><li class=\"small-body\"><p>Sospensione, licenziamento, licenziamento o misure equivalenti.<\/p><\/li><li class=\"small-body\"><p>Retrocessione o rifiuto di promozione<\/p><\/li><li class=\"small-body\"><p>Trasferimento di mansioni, cambio di sede di lavoro, riduzione dello stipendio o modifica dell&#8217;orario di lavoro.<\/p><\/li><li class=\"small-body\"><p>Una valutazione negativa del rendimento o una referenza lavorativa priva di fondamento<\/p><\/li><li class=\"small-body\"><p>L&#8217;imposizione o la somministrazione di qualsiasi misura disciplinare, rimprovero o altra sanzione, inclusa una sanzione pecuniaria.<\/p><\/li><li class=\"small-body\"><p>Coercizione, intimidazione, molestie o ostracismo<\/p><\/li><li class=\"small-body\"><p>Discriminazione, trattamento svantaggioso o ingiusto<\/p><\/li><li class=\"small-body\"><p>La mancata conversione di un contratto di lavoro temporaneo in uno a tempo indeterminato, quando avevi la legittima aspettativa che ti sarebbe stato offerto un lavoro a tempo indeterminato<\/p><\/li><li class=\"small-body\"><p>Mancato rinnovo o risoluzione anticipata di un contratto di lavoro temporaneo<\/p><\/li><li class=\"small-body\"><p>Provocare o minacciare di provocare danni alla persona che fa la denuncia, ai suoi familiari, ai suoi beni personali o alla sua reputazione.<\/p><\/li><li class=\"small-body\"><p>Risoluzione anticipata o annullamento di un contratto per beni o servizi.<\/p><\/li><\/ul><p class=\"small-body\">Se sei stato minacciato o se sono state prese misure contro di te dopo aver parlato di una tua preoccupazione genuina\/legittima o dopo aver collaborato a un&#8217;indagine o a un&#8217;inchiesta, devi parlarne.<\/p><p class=\"small-body\">Univers adotter\u00e0 tempestivamente misure correttive per affrontare qualsiasi caso di ritorsione riscontrato o sospettato. La ritorsione o la minaccia di ritorsione \u00e8 una questione disciplinare che pu\u00f2 portare al licenziamento. Le ritorsioni possono anche costituire una violazione delle leggi e dei regolamenti vigenti, con conseguenti potenziali responsabilit\u00e0 civili e sanzioni penali.  <\/p><p class=\"small-body\">\u00c8 importante notare che se sei stato coinvolto in una condotta scorretta, potresti non ricevere le stesse tutele previste da questa Politica facendo una segnalazione sulla condotta scorretta in cui sei stato coinvolto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49cc959 elementor-widget elementor-widget-text-editor\" data-id=\"49cc959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"header-1\"><strong>5. DUBBI E DOMANDE SULLA POLITICA<\/strong><\/h2><p class=\"small-body\">Se ritieni che un problema sollevato ai sensi della presente Politica non sia stato gestito correttamente, se non sei soddisfatto dell&#8217;esito di una segnalazione o se temi di subire ritorsioni, puoi rivolgerti direttamente all&#8217;Ufficio Legale e di Conformit\u00e0.<\/p><p class=\"small-body\">Qualsiasi domanda relativa a questa Politica pu\u00f2 essere rivolta anche all&#8217;Ufficio Legale e di Conformit\u00e0. Il nostro indirizzo e-mail \u00e8: compliance@unviers.com <\/p><h2> <\/h2><h2> <\/h2><h2><strong>ALLEGATO A<\/strong><\/h2><p class=\"small-body\"><img decoding=\"async\" id=\"11106057\" title=\"\" src=\"https:\/\/a.storyblok.com\/f\/223827\/1334x1342\/5872d96b98\/screenshot-2023-09-14-at-8-59-10-am.png\" alt=\"\"><\/p><h2> <\/h2><h2 class=\"small-body\"><strong>ALLEGATO B<\/strong><\/h2><p class=\"small-body\"><strong>Il codice organizzativo di Univers \u00e8: &#8211; 108664<\/strong><\/p><p class=\"small-body\"><strong> <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad57d4 elementor-widget elementor-widget-html\" data-id=\"7ad57d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t\r\n<div class=\"table-responsive\">\r\n<table class=\"MsoNormalTable\" border=\"1\" cellspacing=\"0\" bgcolor=\"#fff\" cellpadding=\"0\" style=\"border-collapse:collapse;mso-table-layout-alt:fixed; border:none;mso-border-alt:solid black .5pt;mso-yfti-tbllook:480;mso-padding-alt: 0in 0in 0in 0in;mso-border-insideh:.5pt solid black;mso-border-insidev:.5pt solid black\">\r\n <tr style=\"mso-yfti-irow:0;mso-yfti-firstrow:yes;height:15.45pt; margin-left:15px;\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; mso-border-alt:solid black .5pt;background:#CCCCCC;padding:0in 0in 0in 0in; height:15.45pt\">\r\n  <p class=\"TableParagraph\"><b style=\"mso-bidi-font-weight:normal\"><span style=\"font-size:10.0pt;margin-left:5.6pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Country<\/span><\/b><b style=\"mso-bidi-font-weight:normal\"><span style=\"font-size:10.0pt;mso-bidi-font-size: 11.0pt\"><o:p><\/o:p><\/span><\/b><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border:solid black 1.0pt; border-left:none;mso-border-left-alt:solid black .5pt;mso-border-alt:solid black .5pt; background:#CCCCCC;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><b style=\"mso-bidi-font-weight:normal\"><span style=\"font-size:10.0pt;mso-bidi-font-size:11.0pt; margin-left:5.4pt\">Phone <span style=\"letter-spacing:-.1pt\">number<\/span>\r\n        <o:p><\/o:p><\/span><\/b><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border:solid black 1.0pt; border-left:none;mso-border-left-alt:solid black .5pt;mso-border-alt:solid black .5pt; background:#CCCCCC;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><b style=\"mso-bidi-font-weight: normal\"><span style=\"font-size:10.0pt;mso-bidi-font-size:11.0pt\">Phone <span style=\"letter-spacing:-.1pt\">instructions<\/span>\r\n        <o:p><\/o:p><\/span><\/b><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:1;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Albania<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt; margin-left:10pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0035545301801<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +35545301801 Call charged at local rate\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:2;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Algeria<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00213983299338<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +213983299338 Call charged at local rate<o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:3;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Angola<\/span><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt; margin-left:10px; border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00244226425610<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +244226425610 Call charged at local rate<o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:4;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Anguilla<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18334222005<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18334222005<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:5;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Antigua and Barbuda <\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18334222006<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18334222006<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:6;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Argentina<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">00541120397280<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Number : +541120397280 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:7;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Australia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0061282846262<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +61282846262 Call charged at local rate\r\n    <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:8;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Austria<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0800909683<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0800909683<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:9;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Bahamas<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18334222007<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18334222007<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:10;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Bahrain<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0097316501936<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +97316501936<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:11;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Bangladesh<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">008809610998462<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : +880(0)9610<span style=\"letter-spacing:-.1pt\">998462<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:12;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Barbados<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0012466239631<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +1(246)6239631 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:13;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Belgium<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">080089326<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 080089326<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:14;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Belize<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18000130076<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18000130076<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:15;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Benin<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0022920900380<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +22920900380 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:16;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Bermuda<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18334222008<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18334222008<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:17;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Bhutan<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">009752379003<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : +9752379003<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:18;height:26.35pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Bolivia, Plurinational State of\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">800105122<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 800105122<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:19;height:26.25pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.25pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Bosnia and Herzegovina\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.25pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0038770330093<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.25pt\">\r\n    <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +38770330093\r\n  Call charged at local rate\r\n    <o:p><\/o:p><\/span><\/p><\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:20;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Botswana<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">8007861103<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\"><p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Freephone : 8007861103<\/span>\r\n        <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:21;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Brazil<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00551147008838<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +55(11)47008838 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:22;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Brunei <span style=\"letter-spacing:-.1pt\">Darussalam<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">8014657<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 8014657<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:23;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Bulgaria<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">8002100645<\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Freephone : 800210\r\n  0645\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:24;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Burkina Faso\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0022625300982<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +22625300982 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:25;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Cambodia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">1800209867<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 1800209867<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:26;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Cameroon<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">00237657103112<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Freephone : +237657103112<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:27;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Canada<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0015143950496<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +1(514)3950496 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:28;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Cayman<span style=\"letter-spacing:-.1pt\"> Islands<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0013457695580<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +1(345)7695580 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:29;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Chile<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">0056224835917<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Number : +56224835917 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:30;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">China<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">108001523042<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone (via China Telecom):10800152<span style=\"letter-spacing:-.2pt\">3042<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:31;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">China<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">108008522221<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone (Via China United Network) : 10800852<span style=\"letter-spacing:-.2pt\">2221<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:32;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Colombia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">00576012421247<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Number : +576012421247 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:33;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Costa Rica\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0050640360350<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +50640360350 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:34;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">C\u00f4te <span style=\"letter-spacing:-.1pt\">d'Ivoire<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">002250566770918<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone:+2250566770918<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:35;mso-yfti-lastrow:yes;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Croatia<\/span><span style=\"font-size:10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">08007745<\/span><span style=\"font-size:10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Freephone : 08007745<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:0;mso-yfti-firstrow:yes;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Cyprus<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border:solid black 1.0pt; border-top:none;mso-border-left-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">80091142<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border:solid black 1.0pt; border-top:none;mso-border-left-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone :  800<span style=\"letter-spacing: -.1pt\">91142<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:1;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Czechia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">800050833<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone :  800050833<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:2;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Denmark<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">004543310961<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number :  +4543310961 Call charged at local rate\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:3;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Dominica<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18334221998<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18334221998<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:4;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Dominican <span style=\"letter-spacing:-.1pt\">Republic<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0018299471996<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number :  +1(829)9471996 Call charged at local rate \r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:5;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Ecuador<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">1800001432<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 1800001432<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:6;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Egypt<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">08000000083<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 08000000083<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:7;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">El<span style=\"letter-spacing:-.1pt\">Salvador<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0050322304752<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +50322304752  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:8;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Estonia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">003726093008<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number :  +3726093008  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:9;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Ethiopia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">800861919<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 800861919<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:10;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.2pt\">Fiji<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">008002650<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 008002650<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:11;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Finland<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">0800392912<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Freephone : 0800392<span style=\"letter-spacing:-.25pt\">912<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:12;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">France<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0805543753<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0805543753<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:13;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">French <span style=\"letter-spacing:-.1pt\">Guiana<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0800991448<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0800991448<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:14;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">French<span style=\"letter-spacing:-.1pt\"> Polynesia<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0800914886<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0800914886<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:15;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Georgia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">1800008013<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 1800008013<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:16;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Germany<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">08001818952<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 08001818952<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:17;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Ghana<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00233596993553<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +233596993553  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:18;height:26.35pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Greece<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0080044145924<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt; margin-bottom: 0in;\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0080044145924 The number will not <span style=\"letter-spacing:-.2pt\">work<\/span>\r\n      <o:p><\/o:p><\/span><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">when called from a <span style=\"letter-spacing:-.1pt\">mobile<\/span>\r\n      <o:p><\/o:p>\r\n      <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:19;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Grenada<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0014732300333<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +1(473)2300333  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:20;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.2pt\">Guam<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18338096777<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18338096777<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:21;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Guatemala<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0050223028459<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +50223028459  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:22;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Hong Kong\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0085230194193<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +85230194193  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:23;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Hungary<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0680984589<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 06809845<span style=\"letter-spacing: -.25pt\"> 89<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:24;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Iceland<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">003544150349<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +3544150349  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:25;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">India<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0008000503159<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0008000503159<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:26;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Indonesia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00622180630074<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +622180630074  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:27;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Ireland<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">1800800636<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 1800800636<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:28;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Israel<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0097233741225<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n    <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +97233741225\r\n   Call charged at local rate\r\n   <o:p><\/o:p>\r\n   <o:p><\/o:p><\/span><\/p><\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:29;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Italy<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">800147694<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 800147694<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:30;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Jamaica<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0018766779125<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n    <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +1(876)6779125\r\n   Call charged at local rate\r\n   <o:p><\/o:p>\r\n   <o:p><\/o:p><\/span><\/p><\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:31;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Japan<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0081366270734<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +81366270734  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:32;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Jordan<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">080023801<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 080023801 No mobile <span style=\"letter-spacing:-.1pt\">access<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:33;height:26.4pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.4pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Kazakhstan<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.4pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00787273574582<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.4pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt; margin-bottom: 0in;\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +7(8727)3574582 Call charged at local rate\r\n      <o:p><\/o:p>\r\n      ; <span style=\"letter-spacing:-.25pt\">No<\/span>\r\n      <o:p><\/o:p><\/span><span style=\"font-size:10.0pt;mso-bidi-font-size:11.0pt\">mobile <span style=\"letter-spacing:-.1pt\">access<\/span>\r\n      <o:p><\/o:p>\r\n      <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:34;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Kenya<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00254207650957<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +254207650957  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:35;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\">The Republic of Korea\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">0082232761660<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Number : +82232761660 <span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"> Call charged at local rate\r\n        <o:p><\/o:p>\r\n  <\/span><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:36;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Kuwait<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0096522055730<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : +96522055730<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:37;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Latvia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">80005929<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 800<span style=\"letter-spacing: -.1pt\">05929<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:38;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Lebanon<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">8338160193<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Freephone : 8338160193<o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:39;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Lithuania<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">880030366<\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 880030366<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:40;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Luxembourg<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">003523420808982<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +3523420808982  Call charged at local rate\r\n      <o:p><\/o:p>\r\n  <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:41;mso-yfti-lastrow:yes;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Malaysia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">0060377243136<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Number : +60377243136 <span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"> Call charged at local rate\r\n        <o:p><\/o:p>\r\n  <\/span><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n  <tr style=\"mso-yfti-irow:0;mso-yfti-firstrow:yes;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 0.5pt; border-top:none; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Malta<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border:solid black 1.0pt; border-top:none;mso-border-left-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">80065144<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border:solid black 1.0pt; border-top:none;mso-border-left-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 80065144<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:1;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Martinique<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0800901651<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0800901651<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:2;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Mauritius<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0023052970999<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +23052970999 Call charged at local rate\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:3;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Mexico<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00525547806198<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +525547806198 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:4;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size: 11.0pt\">Moldova, Republic <span style=\"letter-spacing:-.25pt\">of<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">080060016<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 080060016<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:5;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Morocco<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00212530144108<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:7.65pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +212530144108 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:6;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Myanmar<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">08008008062<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 08008008062<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:7;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Namibia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00264833800103<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : +264833800103<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:8;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Nepal<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18000010186<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18000010186<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:9;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Netherlands<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0031107007503<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +31107007503 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:10;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">New<span style=\"letter-spacing:-.1pt\"> Zealand<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">006499135892<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +6499135892 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:11;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">Nicaragua<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">0050575137610<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.1pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Number : +50575137610<span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"> Call charged at local rate<\/span><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:12;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Nigeria<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">07080601221<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 07080601221<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:13;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">North<span style=\"letter-spacing:-.1pt\"> Macedonia<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0038925513216<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +38925513216 Call charged at local rate\r\n    <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:14;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Norway<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">004724140601<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +4724140601 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:15;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.2pt\">Oman<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">80074161<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 80074161<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:16;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Pakistan<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0080090044437<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0080090044437<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:17;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Panama<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">005073084480<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +5073084480 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:18;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Papua New<span style=\"letter-spacing:-.1pt\"> Guinea<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">000861322<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 000861322<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:19;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Paraguay<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0098004410266<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0098004410266 No mobile<span style=\"letter-spacing:-.1pt\"> access<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:20;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.2pt\">Peru<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">080074535<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 080074535<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:21;height:26.35pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Philippines<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">180083948474<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 180083948474 Can only be connected by Globe Telecom device \r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:22;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Poland<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00800012953<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 00800012953<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:23;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Portugal<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">800831302<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 800831302<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:24;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Puerto Rico\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0017872007305<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +1(787)2007305  Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:25;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Qatar<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">800101094<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 800101094<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:26;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">R\u00e9union<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">1800916980<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 1800916980<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:27;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Romania<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0800400653<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0800400653<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:28;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Serbia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0038110520043<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +38110520043  Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:29;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Seychelles<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">800131<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 800131<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:30;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Singapore<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">006564037051<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +6564037051  Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:31;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Slovakia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0800113418<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0800113418<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:32;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Slovenia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">080083115<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 080083115<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:33;height:15.6pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.6pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">South<span style=\"letter-spacing:-.1pt\"> Africa<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.6pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0027214277937<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.6pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +27(21)4277937  Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:34;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Spain<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0034900031156<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +34900031156  Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:35;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Sri Lanka<o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0094720910370<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number :  +94(72)0910370 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:36;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Sudan<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00249156559883<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : +249156559883<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:37;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Suriname<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">8338160919<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 8338160919<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:38;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Sweden<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0201604703<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0201604703<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:39;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Switzerland<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0800005691<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0800005691<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:40;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Taiwan<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00886277438912<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number :  +886277438912 Call charged at local rate<\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:41;mso-yfti-lastrow:yes;height:26.35pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">The United Republic of Tanzania<span style=\"letter-spacing:-.1pt\"><\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0800111020<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 0800111020<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n \r\n <tr style=\"mso-yfti-irow:0;mso-yfti-firstrow:yes;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Thailand<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border:solid black 1.0pt; border-top:none;mso-border-left-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">006628449693<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border:solid black 0.5pt; border-top:none;mso-border-left-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number :  +6628449693 Call charged at local rate <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:1;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Trinidad and<span style=\"letter-spacing:-.1pt\"> Tobago<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0018682241869<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number :  +1(868)2241869 Call charged at local rate <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:2;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Tunisia<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0021631300338<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +21631300338 Call charged at local rate <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:3;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Turkey<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00800448828602<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone :  00800448828602<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:4;height:26.35pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Turksand Caicos Islands\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18334621355<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone :  18334621355<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:5;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Uganda<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00256414238162<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n    <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +256414238162\r\n  Call charged at local rate\r\n<o:p><\/o:p><\/span><\/p><\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:6;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">United Arab <span style=\"letter-spacing:-.1pt\">Emirates<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">80004440408<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 80004440408<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:7;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">United<span style=\"letter-spacing:-.1pt\"> Kingdom<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">08000224118<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 08000224118<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:8;height:26.35pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">United States of America\r\n      <o:p><\/o:p><\/span><\/p>\r\n\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">0016692887154<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +1(669)2887154 Call charged at local rate <\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:9;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Uruguay<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">000415985762<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 000415985762<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:10;height:26.35pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">The Bolivarian Republic of Venezuela<\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">00582123357722<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:26.35pt\">\r\n    <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +582123357722\r\n  Call charged at local rate\r\n<o:p><\/o:p><\/span><\/p><\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:11;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Viet <span style=\"letter-spacing:-.25pt\">Nam<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">008419003271<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Number : +8419003271 Call charged at local rate\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:12;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt\">Virgin Islands <span style=\"letter-spacing:-.1pt\">(British)<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">18334621356<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : 18334621356<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:13;height:15.55pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\">VirginIslands <span style=\"letter-spacing:-.1pt\">(U.S.)<\/span>\r\n      <o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-top:.15pt\"><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt;letter-spacing:-.1pt\">18337246398<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.55pt\"><p class=\"TableParagraph\" style=\"margin-top:.15pt;margin-right:0in;margin-bottom: 0in;margin-left:5.4pt;margin-bottom:.0001pt\"><span style=\"font-size:10.0pt; mso-bidi-font-size:11.0pt\">Freephone : 18337246398<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n <tr style=\"mso-yfti-irow:14;mso-yfti-lastrow:yes;height:15.45pt\">\r\n  <td width=\"139\" valign=\"top\" style=\"width:104.15pt;border:solid black 1.0pt; border-top:none;mso-border-top-alt:solid black .5pt;mso-border-alt:solid black .5pt; padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">Zimbabwe<\/span><span style=\"font-size:10.0pt; margin-left:5.4pt; mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"126\" valign=\"top\" style=\"width:94.7pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\"><span style=\"font-size:10.0pt; margin-left:5.4pt;mso-bidi-font-size: 11.0pt;letter-spacing:-.1pt\">002638677422010<\/span><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\"><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n  <td width=\"336\" valign=\"top\" style=\"width:252.05pt;border-top:none;border-left: none;border-bottom:solid black 1.0pt;border-right:solid black 1.0pt; mso-border-top-alt:solid black .5pt;mso-border-left-alt:solid black .5pt; mso-border-alt:solid black .5pt;padding:0in 0in 0in 0in;height:15.45pt\">\r\n  <p class=\"TableParagraph\" style=\"margin-left:5.4pt\"><span style=\"font-size: 10.0pt;mso-bidi-font-size:11.0pt\">Freephone : +2638677422010<\/span><o:p><\/o:p><\/span><\/p>\r\n  <\/td>\r\n <\/tr>\r\n<\/table>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bd4950 elementor-widget elementor-widget-text-editor\" data-id=\"3bd4950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div><h3><b> <\/b><\/h3><h4><b>ISTRUZIONI PER L&#8217;UTILIZZO DELLA PIATTAFORMA SPEAKUP<\/b><\/h4><h5><strong>Via web<\/strong><\/h5><p>Fase 1: Tieni pronti carta e penna.<\/p><p>Fase 2: Clicca su <a href=\"https:\/\/univers.speakup.report\/compliance\">https:\/\/univers.speakup.report\/compliance<\/a> per fare rapporto in inglese. In alternativa, puoi scansionare il seguente codice QR: <br><br><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"\" src=\"https:\/\/a.storyblok.com\/f\/223827\/396x382\/5a64830f0b\/screenshot-2023-09-14-at-8-57-07-am.png\" alt=\"\" width=\"205\" height=\"198\"><\/p><\/div><div><figure id=\"attachment_22711\" aria-describedby=\"caption-attachment-22711\" style=\"width: 879px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/login.jpg\" alt=\"\" width=\"879\" height=\"452\"><figcaption id=\"caption-attachment-22711\" class=\"wp-caption-text\">Schermata della piattaforma SpeakUp gestita autonomamente da Univers per la segnalazione via web.<\/figcaption><\/figure><p><br>Passo 3: per creare un nuovo rapporto, clicca sull&#8217;icona &#8220;Nuovo rapporto&#8221;. (Vedi l&#8217;immagine qui sopra)&#8230; <\/p><p>Fase 4: ti verr\u00e0 assegnato un numero di rapporto casuale. Annota il numero perch\u00e9 ti servir\u00e0 per accedere nuovamente in un secondo momento per controllare lo stato del tuo rapporto o per correggerlo o aggiungerlo. Ti verr\u00e0 inoltre richiesto di creare una password. Avrai bisogno della <sup>password1<\/sup> per accedere e del numero di rapporto per controllare il tuo rapporto. (Vedi la schermata qui sotto)    <\/p><figure style=\"width: 1640px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/a.storyblok.com\/f\/223827\/1640x956\/c0a55688b5\/screenshot-2023-09-14-at-8-57-34-am.png\" alt=\"\" width=\"1640\" height=\"956\"><figcaption class=\"wp-caption-text\"><sup>1Le password<\/sup>devono avere una lunghezza minima di 12 caratteri e devono contenere almeno: un numero, una lettera maiuscola, una lettera minuscola e un carattere speciale (!@#$%^&amp;*<\/figcaption><\/figure><p><br>Passo 5: Scrivi il tuo messaggio. Se vuoi includere un allegato (ad esempio una foto), clicca sull&#8217;icona della graffetta nella pagina del messaggio (vedi lo screenshot qui sotto). <\/p><p><strong>Usa l&#8217;icona della graffetta per gli allegati<\/strong><\/p><p>Fase 6: Quando hai finito, clicca su &#8220;Invia messaggio&#8221; per lasciare la tua segnalazione.<br><br><img decoding=\"async\" title=\"\" src=\"https:\/\/a.storyblok.com\/f\/223827\/1636x734\/ea36500dd0\/screenshot-2023-09-14-at-8-57-40-am.png\" alt=\"\"><br><br>Fase 7: ti verr\u00e0 chiesto se vuoi confermare l&#8217;invio del rapporto. Se vuoi rivedere il tuo rapporto, clicca sul pulsante &#8220;Annulla&#8221;. Se sei sicuro di voler inviare il rapporto, clicca su &#8220;Invia&#8221;.  <br><br><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"\" src=\"https:\/\/a.storyblok.com\/f\/223827\/1102x700\/0d89fcebec\/screenshot-2023-09-14-at-8-57-50-am.png\" alt=\"\" width=\"360\" height=\"228\"><\/p><p>Fase 8: Riceverai una conferma dell&#8217;invio del tuo rapporto. Non dimenticare di conservare il numero del tuo rapporto come indicato nell&#8217;avviso di conferma. (vedi esempio di conferma di invio del rapporto qui sotto).  <\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"\" src=\"https:\/\/a.storyblok.com\/f\/223827\/1102x750\/e9cfd326b5\/screenshot-2023-09-14-at-8-57-54-am.png\" alt=\"\" width=\"360\" height=\"245\"><\/p><p>Fase 9: Controlla lo stato del tuo rapporto dopo una settimana. I team di Triage o di Investigazione potrebbero aver bisogno di ulteriori informazioni o aggiornarti sullo stato della revisione del tuo rapporto. Per farlo, torna allo stesso URL, inserisci il numero del tuo rapporto e la password. Sebbene tu abbia la possibilit\u00e0 di lasciare il tuo indirizzo e-mail, ti preghiamo di <b><u>non<\/u><\/b> farlo.   <\/p><h5><b>Tramite il telefono<\/b><\/h5><p>Fase 1: Tieni pronti carta e penna.<\/p><p>Fase 2: componi il numero di telefono del paese in cui ti trovi. (Fare riferimento all&#8217;Allegato B). Si noti che la maggior parte dei Paesi, ma non tutti, dispone di un numero verde da chiamare per effettuare la segnalazione.  <\/p><p>Passo 3. Il messaggio vocale ti chieder\u00e0 il tuo &#8220;Codice dell&#8217;organizzazione&#8221;. Digita il nostro <strong>codice organizzazione: 108664. <\/strong>(A differenza del rapporto web, il codice dell&#8217;organizzazione \u00e8 comunque necessario nel rapporto telefonico).  <\/p><p>Passo 4: seleziona la lingua in cui vuoi lasciare il tuo messaggio.<\/p><p>Fase 5: Riceverai un numero casuale chiamato &#8220;numero di rapporto&#8221;. Annota il numero di rapporto che ti servir\u00e0 per verificare lo stato del tuo rapporto. <\/p><p>Fase 6: Ti verr\u00e0 chiesto di creare un codice PIN. Avrai bisogno del tuo Codice PIN\/Numero PIN anche per controllare lo stato del tuo rapporto o se vuoi correggerlo o aggiungerlo. <\/p><p>Fase 7: Dopo il tono, pronuncia il tuo messaggio. Assicurati di pronunciare in modo chiaro e possibilmente di scandire i nomi o le localit\u00e0. Il tuo messaggio sar\u00e0 registrato perch\u00e9 non parlerai direttamente con una persona all&#8217;altro capo della linea.  <\/p><p>Fase 8: Una volta terminato il messaggio, premi 1 o riaggancia.<\/p><h5><b>Tramite l&#8217;App SpeakUp<\/b><\/h5><p>Passo 1: Scarica l&#8217;applicazione SpeakUp People Intouch dall&#8217;App Store\/Google Play. Scansiona il seguente codice QR:- <\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speakup.jpg\" alt=\"\" width=\"205\" height=\"201\"><\/p><p>L&#8217;applicazione si presenta cos\u00ec: &#8211;<\/p><p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/soeakup.jpg\" alt=\"\" width=\"1004\" height=\"776\"><\/p><p>Fase 2: Apri l&#8217;applicazione per impostare il tuo codice PIN\/Numero PIN cliccando su &#8220;Imposta il tuo Pin&#8221;.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/enterpin.jpg\" alt=\"\" width=\"305\" height=\"433\"><\/p><p>Fase 3: inserisci il codice PIN scelto e ricordalo. Inserisci lo stesso Codice PIN\/Numero PIN per confermare nuovamente. In caso contrario, dovrai disinstallare e reinstallare l&#8217;applicazione sul tuo dispositivo e non potrai accedere al tuo report.  <\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/pin.jpg\" alt=\"\" width=\"305\" height=\"379\"><\/p><p>Fase 4: L&#8217;applicazione ti chieder\u00e0 di connetterti alla tua organizzazione scansionando il codice QR o di &#8220;Connetterti manualmente&#8221;. Seleziona &#8220;Connetti manualmente&#8221;. <\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/scan.jpg\" alt=\"\" width=\"305\" height=\"423\"><\/p><p>Fase 5: Inserisci il codice dell&#8217;organizzazione (il codice della nostra azienda \u00e8: 10365) Ora puoi creare il tuo rapporto quando vedrai la seguente schermata. Premi il pulsante &#8220;+ Nuovo rapporto&#8221;. <\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/speakupline.jpg\" alt=\"\" width=\"305\" height=\"484\"><\/p><p>Fase 7: Puoi scrivere il tuo rapporto o registrare un messaggio. Clicca su &#8220;<strong>Scrivi un messaggio<\/strong>&#8221; e clicca sull&#8217;angolo in alto a destra per modificare le impostazioni della lingua. In alternativa, clicca su &#8220;Registra un messaggio vocale&#8221; per lasciare un messaggio vocale. (Se lasci un messaggio vocale, questo verr\u00e0 trascritto e l&#8217;amministratore e\/o il team investigativo di Univers&#8217; potranno leggere solo la trascrizione del tuo messaggio vocale. Non potranno ascoltarlo).   <\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/lang.jpg\" alt=\"\" width=\"305\" height=\"438\"><\/p><p>Passo 8: se vuoi scrivere il tuo messaggio invece di lasciare un messaggio vocale, scrivi il tuo messaggio nella casella di testo aperta; carica eventuali documenti necessari utilizzando l&#8217;icona della graffetta. Una volta terminato, clicca sull&#8217;icona dell&#8217;aeroplanino per inviare. <\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/message.jpg\" alt=\"\" width=\"305\" height=\"456\"><\/p><p>Fase 9: ti verr\u00e0 chiesto di controllare nuovamente il tuo messaggio; se vuoi modificarlo, clicca su &#8220;<strong>Annulla<\/strong>&#8220;; se vuoi inviarlo, clicca su &#8220;<strong>Invia<\/strong>&#8220;.<\/p><p>Passo 10: Clicca su &#8220;<strong>S\u00ec, avvisami<\/strong>&#8221; se vuoi ricevere notifiche quando c&#8217;\u00e8 una risposta.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/thankyou.jpg\" alt=\"\" width=\"305\" height=\"435\"><\/p><p>Fase 11: Effettua nuovamente il login dopo una settimana per verificare lo stato del tuo rapporto.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/report.jpg\" alt=\"\" width=\"305\" height=\"419\"><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5067c6f elementor-widget elementor-widget-text-editor\" data-id=\"5067c6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ultima modifica: 31 mar 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1135249154\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1135249154\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\" elementor-element elementor-element-4cfb316 e-flex e-con-boxed e-con e-child\" data-id=\"4cfb316\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb02d6 elementor-widget elementor-widget-text-editor\" data-id=\"2eb02d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"PolicySection_details__06Tlf\"><h2 class=\"small-body\"><strong>Dichiarazione di Univers sulla schiavit\u00f9 moderna<\/strong><\/h2><p class=\"small-body\">La presente dichiarazione illustra le misure che Univers e le nostre controllate hanno adottato in relazione alle nostre responsabilit\u00e0 ai sensi del Modern Slavery Act 2015 del Regno Unito per mitigare il rischio di schiavit\u00f9 moderna nelle nostre attivit\u00e0 e nella nostra catena di fornitura nell&#8217;esercizio finanziario conclusosi il 31 dicembre 2024.<\/p><p class=\"small-body\">Per &#8220;Persone Univers&#8221; si intendono tutti i membri di Univers, come i dipendenti (a tempo pieno e parziale), i lavoratori a contratto, i consulenti, i funzionari e gli amministratori di Univers.<br><br><\/p><h2 class=\"header-1\"><strong>Introduzione<\/strong><\/h2><p class=\"small-body\">In Univers abbiamo un approccio di tolleranza zero nei confronti della schiavit\u00f9 moderna in qualsiasi forma, compresi il lavoro forzato, il lavoro minorile, il lavoro vincolato, la tratta di esseri umani e tutte le altre pratiche di sfruttamento. Tutte le organizzazioni, indipendentemente dalla loro ubicazione, sono a rischio di essere coinvolte nel reato di schiavit\u00f9 moderna, in quanto pu\u00f2 verificarsi in qualsiasi punto della catena di fornitura e attraverso le proprie operazioni. <\/p><p class=\"small-body\">Siamo firmatari del Global Compact delle Nazioni Unite e aderiamo ai suoi dieci principi in materia di diritti umani, lavoro, ambiente e lotta alla corruzione.<br><br><\/p><h2 class=\"header-1\"><strong>La nostra attivit\u00e0 e la nostra catena di fornitura<\/strong><\/h2><p class=\"small-body\"><span style=\"letter-spacing: -0.54px;\">In qualit\u00e0 di leader globale nel settore dell&#8217;Al per l&#8217;energia, Univers fornisce soluzioni digitali, attraverso la sua piattaforma proprietaria Energy Al Operating System, EnOS\u2122, che supportano la decarbonizzazione dei sistemi energetici. Le sue offerte comprendono la gestione delle prestazioni energetiche, l&#8217;ottimizzazione delle energie rinnovabili e il controllo della ricarica dei veicoli elettrici. L&#8217;azienda gestisce pi\u00f9 di 20 uffici in 11 paesi: Singapore (la nostra sede centrale), Cina, Francia, Germania, India, Giappone, Malesia, Norvegia, Paesi Bassi, Regno Unito e Stati Uniti.  <br><\/span><\/p><p class=\"small-body\"><span style=\"letter-spacing: -0.54px;\">La nostra attivit\u00e0 in tutte le sedi \u00e8 basata su uffici, supportati da una rete di fornitori che forniscono beni e servizi, come servizi cloud, applicazioni software, sistemi informatici, servizi professionali, manodopera in outsourcing e altre operazioni in outsourcing. Abbiamo instaurato e continueremo a mantenere un rapporto di fiducia e integrit\u00e0 con tutti i nostri fornitori, basato su fattori reciprocamente vantaggiosi. <br><br><\/span><\/p><\/div><h2 class=\"header-1\"><strong>Politiche<\/strong><\/h2><p class=\"small-body\">Univers ha adottato diverse politiche per valutare e affrontare i rischi della schiavit\u00f9 moderna. Tali politiche sono consultabili alla pagina Panoramica delle politiche e comprendono: <\/p><ul><li class=\"small-body\">Codice di Condotta &#8211; impegna tutte le Persone Universitarie a rispettare i pi\u00f9 alti standard di integrit\u00e0 e stabilisce il nostro impegno a rispettare i diritti umani e la dignit\u00e0 di ogni persona con cui abbiamo a che fare durante la nostra attivit\u00e0.<\/li><li class=\"small-body\">Codice di condotta per i fornitori &#8211; vieta esplicitamente tutte le forme di schiavit\u00f9 moderna e richiede a tutti i fornitori di firmare e riconoscere la loro conformit\u00e0 alle leggi sul lavoro e agli standard internazionali sui diritti umani.<\/li><li class=\"small-body\">Politica di Due Diligence per le terze parti &#8211; garantisce l&#8217;identificazione e la valutazione dei rischi di schiavit\u00f9 moderna sia al momento dell&#8217;assunzione che per tutta la durata del nostro impegno con le terze parti.<\/li><\/ul><h2 class=\"header-1\"><br><strong>Processi di due diligence<\/strong><\/h2><p class=\"small-body\">Esaminiamo tutti i nuovi fornitori alla luce di considerazioni ambientali e sociali, tra cui la loro reputazione, il rispetto della legge, la conformit\u00e0 agli standard ambientali, sanitari e di sicurezza e l&#8217;impegno nei confronti dei principi del Global Compact delle Nazioni Unite. Oltre alla due diligence durante la fase di inserimento, effettuiamo verifiche continue di due diligence sui fornitori di servizi terzi esistenti. Le terze parti a pi\u00f9 alto rischio sono sottoposte a una due diligence rafforzata e possono essere obbligate a fornire ulteriore documentazione o piani d&#8217;azione correttivi.  <br><br><\/p><div class=\"PolicySection_details__06Tlf\"><h2 class=\"header-1\"><strong>Valutazione del rischio<\/strong><\/h2><p class=\"small-body\">Effettuiamo valutazioni annuali del rischio della nostra catena di fornitura valutando la geografia, il settore industriale e la natura dei beni o dei servizi forniti. Questa valutazione determina la nostra risposta e i controlli di rischio che implementiamo, consentendoci di adottare un approccio proattivo e basato sul rischio per gestire i rischi di schiavit\u00f9 moderna nelle nostre operazioni e nella nostra catena di fornitura. <\/p><p class=\"small-body\">Abbiamo valutato che i rischi intrinseci di violazione dei diritti umani nelle nostre operazioni e nel nostro cambiamento di valore sono bassi a causa della natura della nostra attivit\u00e0 nel settore tecnologico. Sebbene i lavoratori in outsourcing costituiscano pi\u00f9 della met\u00e0 della nostra forza lavoro totale, in genere impieghiamo professionisti qualificati che hanno un&#8217;esposizione minima alle pratiche di schiavit\u00f9 moderna e adottiamo inoltre misure proattive per gestire questo rischio, ingaggiando solo agenzie affidabili che rispettano le leggi e i regolamenti in materia di occupazione. <br><br><\/p><h2 class=\"header-1\"><strong>Formazione e sensibilizzazione<\/strong><\/h2><p class=\"small-body\">Comunichiamo il nostro Codice e le relative politiche a tutte le Persone Univers e rendiamo il nostro Codice e le nostre politiche facilmente disponibili. Univers fornisce anche il materiale di formazione relativo a queste politiche e moduli di formazione sui diritti umani e sulla schiavit\u00f9 moderna attraverso le nostre piattaforme di formazione di terzi. <br><br><\/p><h2 class=\"header-1\"><strong>Whistleblowing<\/strong><\/h2><p class=\"small-body\">Il Gruppo incoraggia tutti i suoi dipendenti, le terze parti o le controparti (ad esempio clienti e altri partner commerciali) a segnalare qualsiasi preoccupazione relativa alle attivit\u00e0 dirette o alle catene di fornitura dell&#8217;organizzazione. Ci\u00f2 include qualsiasi circostanza che possa dare origine a un rischio maggiore di schiavit\u00f9 o traffico di esseri umani. <\/p><p class=\"small-body\">Univers dispone di un canale di segnalazione per consentire a terzi, come clienti, fornitori, dipendenti e appaltatori, di segnalare eventuali casi di illecito.<\/p><p class=\"small-body\">Il canale per le segnalazioni di irregolarit\u00e0 \u00e8 stato progettato per consentire a chiunque di fare segnalazioni senza timore di ritorsioni. I dipendenti che hanno dei dubbi possono utilizzare il nostro approccio riservato attraverso la piattaforma Speak Up. Questo approccio di segnalazione indipendente viene ampiamente annunciato ai dipendenti e ai fornitori di tutto il mondo e monitorato dal dipartimento di conformit\u00e0 globale di Univers.  <\/p><p class=\"small-body\">In alternativa, le segnalazioni possono essere fatte dai dipendenti che informano il proprio manager di riferimento o un membro senior delle Risorse Umane, il quale condurr\u00e0 o far\u00e0 condurre un&#8217;indagine anonima a un individuo senior.<\/p><p class=\"small-body\">In tutti i percorsi di divulgazione, nel 2024 non sono state effettuate chiamate o divulgazioni dirette in relazione alla schiavit\u00f9 moderna e alla tratta di esseri umani.<br><br><\/p><h2 class=\"header-1\"><strong>Valutare l&#8217;efficacia delle nostre azioni<\/strong><\/h2><p class=\"small-body\">Rivediamo regolarmente le nostre politiche, procedure e sistemi per garantirne la solidit\u00e0 e la conformit\u00e0 ai requisiti normativi, oltre a sostenere e rispettare gli standard e i principi internazionali in materia di diritti umani e del lavoro stabiliti dalla Dichiarazione Universale dei Diritti Umani delle Nazioni Unite e dall&#8217;Organizzazione Internazionale del Lavoro.<\/p><p class=\"small-body\">Abbiamo anche valutato le nostre attivit\u00e0 commerciali in relazione alla tassonomia dell&#8217;UE, laddove soddisfano le garanzie sociali minime, ovvero le Linee guida dell&#8217;OCSE per le imprese multinazionali e i Principi guida delle Nazioni Unite su imprese e diritti umani. Per valutare l&#8217;efficacia del nostro approccio vengono monitorati indicatori chiave come la percentuale di fornitori controllati, le segnalazioni o gli incidenti sollevati in relazione a violazioni del lavoro e i tassi di completamento della formazione. <br><br><\/p><h2 class=\"header-1\"><strong>Guardare avanti<\/strong><\/h2><p class=\"small-body\">Con la crescita della nostra azienda, crescono anche l&#8217;importanza, il numero e la portata delle relazioni nelle nostre catene di fornitura. Continuiamo a prendere provvedimenti per valutare le aree in cui la schiavit\u00f9 moderna potrebbe essere una possibilit\u00e0 e a studiare i meccanismi migliori e pi\u00f9 efficaci per gestire questi rischi. <br><br><\/p><h2 class=\"header-1\"><strong>Firma<\/strong><\/h2><p class=\"small-body\">In conformit\u00e0 con il Modern Slavery Act 2015 del Regno Unito e le relative linee guida, la presente Dichiarazione copre il periodo compreso tra il 1\u00b0 gennaio 2024 e il 31 dicembre 2024. \u00c8 stata approvata dal Consiglio di amministrazione il 29 aprile 2025 e sar\u00e0 rivista e aggiornata annualmente. <\/p><h4 class=\"header-1\"> <\/h4><h4 class=\"header-1\">Autorizzato da :<\/h4><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-22745\" src=\"https:\/\/univers.com\/wp-content\/uploads\/2025\/05\/erica.jpg\" alt=\"\" width=\"223\" height=\"76\"><\/p><p class=\"small-body\"><strong>Erica Newland <\/strong> <br>Direttore, Univers Pte. Ltd. <\/p><p class=\"small-body\"> <\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ceb9e7b elementor-widget elementor-widget-text-editor\" data-id=\"ceb9e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ultima modifica: 29 aprile 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1135249155\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1135249155\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\" elementor-element elementor-element-355deea e-flex e-con-boxed e-con e-child\" data-id=\"355deea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f03185 elementor-widget elementor-widget-text-editor\" data-id=\"9f03185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"large-header-1\"><span style=\"color: var( --e-global-color-primary ); font-size: 18px; letter-spacing: -0.54px; text-align: var(--text-align); background-color: var( --e-global-color-ddd80fe );\">Univers si impegna a creare un ambiente diversificato, sicuro e inclusivo in cui le nostre persone possano prosperare. In quanto datore di lavoro con pari opportunit\u00e0, tutte le decisioni di assunzione e le opportunit\u00e0 di avanzamento presso Univers si basano sul merito, sulle qualifiche, sulle competenze e sulle capacit\u00e0. I candidati qualificati saranno presi in considerazione per l&#8217;assunzione a prescindere da et\u00e0, razza, sesso, colore della pelle, stato civile, religione, orientamento sessuale, disabilit\u00e0, estrazione sociale o etnica, appartenenza a sindacati o altre caratteristiche non legate al merito.    <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524a741 elementor-widget elementor-widget-text-editor\" data-id=\"524a741\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ultima modifica: 12 ott 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-adc359f e-flex e-con-boxed e-con e-parent\" data-id=\"adc359f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Panoramica delle politiche Panoramica delle politiche Codice di condotta Politica SpeakUp Dichiarazione sulla schiavit\u00f9 moderna Politica di pari opportunit\u00e0 di impiego Costruire una cultura universale della conformit\u00e0 In Univers, dove la connessione \u00e8 tutto, \u00e8 il modo in cui realizzeremo la transizione verso l&#8217;energia verde che i nostri clienti richiedono e di cui il mondo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"page-header":[15],"page-type":[],"class_list":["post-28825","page","type-page","status-publish","hentry","page-header-black"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>- %<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panoramica delle politiche - Univers\" \/>\n<meta property=\"og:description\" content=\"Scopri le politiche di Univers, tra cui la privacy, i termini d&#039;uso, la protezione dei dati e altre importanti linee guida che garantiscono trasparenza e sicurezza a tutti gli utenti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/\" \/>\n<meta property=\"og:site_name\" content=\"Universit\u00e0\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T17:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.storyblok.com\/f\/223827\/155x88\/0e8799f6a9\/image-1836-no-bg.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Il nostro Codice di Condotta | Univers\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"147 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/il-nostro-codice-di-condotta-univers\\\/\",\"url\":\"https:\\\/\\\/univers.com\\\/it\\\/il-nostro-codice-di-condotta-univers\\\/\",\"name\":\"- %\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/il-nostro-codice-di-condotta-univers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/il-nostro-codice-di-condotta-univers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a.storyblok.com\\\/f\\\/223827\\\/155x88\\\/0e8799f6a9\\\/image-1836-no-bg.png\",\"datePublished\":\"2024-09-26T07:38:01+00:00\",\"dateModified\":\"2025-12-16T17:27:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/il-nostro-codice-di-condotta-univers\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/univers.com\\\/it\\\/il-nostro-codice-di-condotta-univers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/il-nostro-codice-di-condotta-univers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/a.storyblok.com\\\/f\\\/223827\\\/155x88\\\/0e8799f6a9\\\/image-1836-no-bg.png\",\"contentUrl\":\"https:\\\/\\\/a.storyblok.com\\\/f\\\/223827\\\/155x88\\\/0e8799f6a9\\\/image-1836-no-bg.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/il-nostro-codice-di-condotta-univers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/univers.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il nostro Codice di Condotta | Univers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/univers.com\\\/it\\\/\",\"name\":\"Univers\",\"description\":\"Leader mondiale nell&#039;AI e nell&#039;IoT per l&#039;energia\",\"publisher\":{\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/univers.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/#organization\",\"name\":\"Universit\u00e0\",\"url\":\"https:\\\/\\\/univers.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/univers.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/LOGO-UNIVERS-BLACK@3x.png\",\"contentUrl\":\"https:\\\/\\\/univers.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/LOGO-UNIVERS-BLACK@3x.png\",\"width\":345,\"height\":63,\"caption\":\"Universit\u00e0\"},\"image\":{\"@id\":\"https:\\\/\\\/univers.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/univers-intl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"- %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/","og_locale":"it_IT","og_type":"article","og_title":"Panoramica delle politiche - Univers","og_description":"Scopri le politiche di Univers, tra cui la privacy, i termini d'uso, la protezione dei dati e altre importanti linee guida che garantiscono trasparenza e sicurezza a tutti gli utenti.","og_url":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/","og_site_name":"Universit\u00e0","article_modified_time":"2025-12-16T17:27:47+00:00","og_image":[{"url":"https:\/\/a.storyblok.com\/f\/223827\/155x88\/0e8799f6a9\/image-1836-no-bg.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Il nostro Codice di Condotta | Univers","twitter_misc":{"Est. reading time":"147 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/","url":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/","name":"- %","isPartOf":{"@id":"https:\/\/univers.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/#primaryimage"},"image":{"@id":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/#primaryimage"},"thumbnailUrl":"https:\/\/a.storyblok.com\/f\/223827\/155x88\/0e8799f6a9\/image-1836-no-bg.png","datePublished":"2024-09-26T07:38:01+00:00","dateModified":"2025-12-16T17:27:47+00:00","breadcrumb":{"@id":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/#primaryimage","url":"https:\/\/a.storyblok.com\/f\/223827\/155x88\/0e8799f6a9\/image-1836-no-bg.png","contentUrl":"https:\/\/a.storyblok.com\/f\/223827\/155x88\/0e8799f6a9\/image-1836-no-bg.png"},{"@type":"BreadcrumbList","@id":"https:\/\/univers.com\/it\/il-nostro-codice-di-condotta-univers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/univers.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il nostro Codice di Condotta | Univers"}]},{"@type":"WebSite","@id":"https:\/\/univers.com\/it\/#website","url":"https:\/\/univers.com\/it\/","name":"Univers","description":"Leader mondiale nell&#039;AI e nell&#039;IoT per l&#039;energia","publisher":{"@id":"https:\/\/univers.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/univers.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/univers.com\/it\/#organization","name":"Universit\u00e0","url":"https:\/\/univers.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/univers.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/univers.com\/wp-content\/uploads\/2024\/09\/LOGO-UNIVERS-BLACK@3x.png","contentUrl":"https:\/\/univers.com\/wp-content\/uploads\/2024\/09\/LOGO-UNIVERS-BLACK@3x.png","width":345,"height":63,"caption":"Universit\u00e0"},"image":{"@id":"https:\/\/univers.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/univers-intl\/"]}]}},"_links":{"self":[{"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/pages\/28825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/comments?post=28825"}],"version-history":[{"count":0,"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/pages\/28825\/revisions"}],"wp:attachment":[{"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/media?parent=28825"}],"wp:term":[{"taxonomy":"page-header","embeddable":true,"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/page-header?post=28825"},{"taxonomy":"page-type","embeddable":true,"href":"https:\/\/univers.com\/it\/wp-json\/wp\/v2\/page-type?post=28825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}